{"id":3318,"date":"2023-03-06T11:28:28","date_gmt":"2023-03-06T11:28:28","guid":{"rendered":"http:\/\/manpro.id\/product\/?page_id=3318"},"modified":"2023-06-21T07:56:25","modified_gmt":"2023-06-21T07:56:25","slug":"reporting","status":"publish","type":"page","link":"https:\/\/manpro.id\/product\/reporting\/","title":{"rendered":"Reporting"},"content":{"rendered":"<p>[av_section min_height=&#8217;custom&#8217; min_height_pc=&#8217;25&#8217; min_height_px=&#8217;500&#8242; shadow=&#8217;no-border-styling&#8217; bottom_border=&#8217;no-border-styling&#8217; bottom_border_diagonal_color=&#8217;#333333&#8242; bottom_border_diagonal_direction=&#8221; bottom_border_style=&#8221; padding=&#8217;default&#8217; custom_margin=&#8217;0px&#8217; custom_margin_sync=&#8217;true&#8217; av-desktop-custom_margin=&#8221; av-desktop-custom_margin_sync=&#8217;true&#8217; av-medium-custom_margin=&#8221; av-medium-custom_margin_sync=&#8217;true&#8217; av-small-custom_margin=&#8221; av-small-custom_margin_sync=&#8217;true&#8217; av-mini-custom_margin=&#8221; av-mini-custom_margin_sync=&#8217;true&#8217; svg_div_top=&#8221; svg_div_top_color=&#8217;#333333&#8242; svg_div_top_width=&#8217;100&#8242; svg_div_top_height=&#8217;50&#8217; svg_div_top_max_height=&#8217;none&#8217; svg_div_top_opacity=&#8221; svg_div_bottom=&#8221; svg_div_bottom_color=&#8217;#333333&#8242; svg_div_bottom_width=&#8217;100&#8242; svg_div_bottom_height=&#8217;50&#8217; svg_div_bottom_max_height=&#8217;none&#8217; svg_div_bottom_opacity=&#8221; color=&#8217;main_color&#8217; background=&#8217;bg_color&#8217; custom_bg=&#8217;#ffffff&#8217; background_gradient_direction=&#8217;vertical&#8217; background_gradient_color1=&#8217;#000000&#8242; background_gradient_color2=&#8217;#ffffff&#8217; background_gradient_color3=&#8221; src=&#8217;http:\/\/manpro.id\/product\/wp-content\/uploads\/2023\/06\/edit-report-4-1210&#215;423.png&#8217; attachment=&#8217;6512&#8242; attachment_size=&#8217;entry_without_sidebar&#8217; attach=&#8217;scroll&#8217; position=&#8217;bottom right&#8217; repeat=&#8217;stretch&#8217; video=&#8221; video_ratio=&#8217;16:9&#8242; overlay_opacity=&#8217;0.5&#8242; overlay_color=&#8221; overlay_pattern=&#8221; overlay_custom_pattern=&#8221; custom_arrow_bg=&#8221; css_position_z_index=&#8221; av-desktop-css_position_z_index=&#8221; av-medium-css_position_z_index=&#8221; av-small-css_position_z_index=&#8221; av-mini-css_position_z_index=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; aria_label=&#8221; av_element_hidden_in_editor=&#8217;0&#8242; av_uid=&#8217;av-f4wra&#8217; sc_version=&#8217;1.0&#8242;]<br \/>\n[av_one_half first min_height=&#8221; vertical_alignment=&#8217;av-align-top&#8217; space=&#8221; row_boxshadow_width=&#8217;10&#8217; row_boxshadow_color=&#8221; margin=&#8217;0px&#8217; margin_sync=&#8217;true&#8217; av-desktop-margin=&#8221; av-desktop-margin_sync=&#8217;true&#8217; av-medium-margin=&#8221; av-medium-margin_sync=&#8217;true&#8217; av-small-margin=&#8221; av-small-margin_sync=&#8217;true&#8217; av-mini-margin=&#8221; av-mini-margin_sync=&#8217;true&#8217; mobile_breaking=&#8221; mobile_column_order=&#8221; border=&#8221; border_style=&#8217;solid&#8217; border_color=&#8221; radius=&#8221; radius_sync=&#8217;true&#8217; min_col_height=&#8217;400&#8242; padding=&#8221; padding_sync=&#8217;true&#8217; av-desktop-padding=&#8221; av-desktop-padding_sync=&#8217;true&#8217; av-medium-padding=&#8221; av-medium-padding_sync=&#8217;true&#8217; av-small-padding=&#8221; av-small-padding_sync=&#8217;true&#8217; av-mini-padding=&#8221; av-mini-padding_sync=&#8217;true&#8217; svg_div_top=&#8221; svg_div_top_color=&#8217;#333333&#8242; svg_div_top_width=&#8217;100&#8242; svg_div_top_height=&#8217;50&#8217; svg_div_top_max_height=&#8217;none&#8217; svg_div_top_opacity=&#8221; svg_div_bottom=&#8221; svg_div_bottom_color=&#8217;#333333&#8242; svg_div_bottom_width=&#8217;100&#8242; svg_div_bottom_height=&#8217;50&#8217; svg_div_bottom_max_height=&#8217;none&#8217; svg_div_bottom_opacity=&#8221; column_boxshadow_width=&#8217;10&#8217; column_boxshadow_color=&#8221; background=&#8217;bg_color&#8217; background_color=&#8221; background_gradient_direction=&#8217;vertical&#8217; background_gradient_color1=&#8217;#000000&#8242; background_gradient_color2=&#8217;#ffffff&#8217; background_gradient_color3=&#8221; src=&#8221; attachment=&#8221; attachment_size=&#8221; background_position=&#8217;top left&#8217; background_repeat=&#8217;no-repeat&#8217; highlight_size=&#8217;1.1&#8242; animation=&#8221; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; parallax_parallax=&#8221; parallax_parallax_speed=&#8221; av-desktop-parallax_parallax=&#8221; av-desktop-parallax_parallax_speed=&#8221; av-medium-parallax_parallax=&#8221; av-medium-parallax_parallax_speed=&#8221; av-small-parallax_parallax=&#8221; av-small-parallax_parallax_speed=&#8221; av-mini-parallax_parallax=&#8221; av-mini-parallax_parallax_speed=&#8221; css_position=&#8221; css_position_location=&#8217;,,,&#8217; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8217;,,,&#8217; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8217;,,,&#8217; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8217;,,,&#8217; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8217;,,,&#8217; av-mini-css_position_z_index=&#8221; link=&#8221; linktarget=&#8221; link_hover=&#8221; title_attr=&#8221; alt_attr=&#8221; mobile_display=&#8221; mobile_col_pos=&#8217;0&#8242; id=&#8221; custom_class=&#8221; template_class=&#8221; aria_label=&#8221; av_uid=&#8217;av-14go9s6&#8242; sc_version=&#8217;1.0&#8242;]<\/p>\n<p>[av_hr class=&#8217;invisible&#8217; icon_select=&#8217;yes&#8217; icon=&#8217;ue808&#8242; font=&#8217;entypo-fontello&#8217; position=&#8217;center&#8217; shadow=&#8217;no-shadow&#8217; height=&#8217;100&#8242; custom_border=&#8217;av-border-thin&#8217; custom_width=&#8217;50px&#8217; custom_margin_top=&#8217;30px&#8217; custom_margin_bottom=&#8217;30px&#8217; custom_border_color=&#8221; custom_icon_color=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-lhinpowa&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<p>[av_textblock textblock_styling_align=&#8221; textblock_styling=&#8221; textblock_styling_gap=&#8221; textblock_styling_mobile=&#8221; size=&#8221; av-desktop-font-size=&#8221; av-medium-font-size=&#8221; av-small-font-size=&#8221; av-mini-font-size=&#8221; font_color=&#8217;custom&#8217; color=&#8217;#e8500e&#8217; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-13mu0xy&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<h3 style=\"font-size: 30px; font-family: Gotham; font-weight: 500; letter-spacing: 0.5px;\">Flexibilitas ruang kerja<br \/>\nsesuai kebutuhan Anda<\/h3>\n<p>[\/av_textblock]<\/p>\n<p>[av_hr class=&#8217;invisible&#8217; icon_select=&#8217;yes&#8217; icon=&#8217;ue808&#8242; font=&#8217;entypo-fontello&#8217; position=&#8217;center&#8217; shadow=&#8217;no-shadow&#8217; height=&#8217;50&#8217; custom_border=&#8217;av-border-thin&#8217; custom_width=&#8217;50px&#8217; custom_margin_top=&#8217;30px&#8217; custom_margin_bottom=&#8217;30px&#8217; custom_border_color=&#8221; custom_icon_color=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-lixwxk18&#8242; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<p>[av_button label=&#8217;Jadwalkan Demo&#8217; icon_select=&#8217;yes&#8217; icon=&#8217;ue8b7&#8242; font=&#8217;entypo-fontello&#8217; link=&#8217;manually,http:\/\/&#8217; link_target=&#8221; size=&#8217;large&#8217; position=&#8217;left&#8217; label_display=&#8221; title_attr=&#8221; size-text=&#8217;22&#8217; av-desktop-font-size-text=&#8221; av-medium-font-size-text=&#8221; av-small-font-size-text=&#8221; av-mini-font-size-text=&#8221; margin=&#8221; margin_sync=&#8217;true&#8217; padding=&#8221; padding_sync=&#8217;true&#8217; av-desktop-margin=&#8221; av-desktop-margin_sync=&#8217;true&#8217; av-desktop-padding=&#8221; av-desktop-padding_sync=&#8217;true&#8217; av-medium-margin=&#8221; av-medium-margin_sync=&#8217;true&#8217; av-medium-padding=&#8221; av-medium-padding_sync=&#8217;true&#8217; av-small-margin=&#8221; av-small-margin_sync=&#8217;true&#8217; av-small-padding=&#8221; av-small-padding_sync=&#8217;true&#8217; av-mini-margin=&#8221; av-mini-margin_sync=&#8217;true&#8217; av-mini-padding=&#8221; av-mini-padding_sync=&#8217;true&#8217; color_options=&#8221; color=&#8217;theme-color&#8217; custom_bg=&#8217;#444444&#8242; custom_font=&#8217;#ffffff&#8217; btn_color_bg=&#8217;theme-color&#8217; btn_custom_grad_direction=&#8217;vertical&#8217; btn_custom_grad_1=&#8217;#000000&#8242; btn_custom_grad_2=&#8217;#ffffff&#8217; btn_custom_grad_3=&#8221; btn_custom_grad_opacity=&#8217;0.7&#8242; btn_custom_bg=&#8217;#444444&#8242; btn_color_bg_hover=&#8217;theme-color-highlight&#8217; btn_custom_bg_hover=&#8217;#444444&#8242; btn_color_font=&#8217;theme-color&#8217; btn_custom_font=&#8217;#ffffff&#8217; btn_color_font_hover=&#8217;white&#8217; btn_custom_font_hover=&#8217;#ffffff&#8217; border=&#8221; border_width=&#8221; border_width_sync=&#8217;true&#8217; border_color=&#8221; border_radius=&#8221; border_radius_sync=&#8217;true&#8217; box_shadow=&#8221; box_shadow_style=&#8217;0px,0px,0px,0px&#8217; box_shadow_color=&#8221; animation=&#8221; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; hover_opacity=&#8221; sonar_effect_effect=&#8221; sonar_effect_color=&#8221; sonar_effect_duration=&#8217;1&#8242; sonar_effect_scale=&#8221; sonar_effect_opac=&#8217;0.5&#8242; css_position=&#8221; css_position_location=&#8217;,,,&#8217; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8217;,,,&#8217; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8217;,,,&#8217; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8217;,,,&#8217; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8217;,,,&#8217; av-mini-css_position_z_index=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-lhyn9j70&#8242; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<p>[\/av_one_half]<br \/>\n[\/av_section]<\/p>\n<p>[av_one_half first min_height=&#8221; vertical_alignment=&#8217;av-align-bottom&#8217; space=&#8217;no_margin&#8217; row_boxshadow_width=&#8217;10&#8217; row_boxshadow_color=&#8221; margin=&#8217;30&#8217; margin_sync=&#8217;true&#8217; av-desktop-margin=&#8221; av-desktop-margin_sync=&#8217;true&#8217; av-medium-margin=&#8221; av-medium-margin_sync=&#8217;true&#8217; av-small-margin=&#8221; av-small-margin_sync=&#8217;true&#8217; av-mini-margin=&#8221; av-mini-margin_sync=&#8217;true&#8217; mobile_breaking=&#8221; mobile_column_order=&#8221; border=&#8221; border_style=&#8217;solid&#8217; border_color=&#8221; radius=&#8221; radius_sync=&#8217;true&#8217; min_col_height=&#8221; padding=&#8221; padding_sync=&#8217;true&#8217; av-desktop-padding=&#8221; av-desktop-padding_sync=&#8217;true&#8217; av-medium-padding=&#8221; av-medium-padding_sync=&#8217;true&#8217; av-small-padding=&#8221; av-small-padding_sync=&#8217;true&#8217; av-mini-padding=&#8221; av-mini-padding_sync=&#8217;true&#8217; svg_div_top=&#8221; svg_div_top_color=&#8217;#333333&#8242; svg_div_top_width=&#8217;100&#8242; svg_div_top_height=&#8217;50&#8217; svg_div_top_max_height=&#8217;none&#8217; svg_div_top_opacity=&#8221; svg_div_bottom=&#8221; svg_div_bottom_color=&#8217;#333333&#8242; svg_div_bottom_width=&#8217;100&#8242; svg_div_bottom_height=&#8217;50&#8217; svg_div_bottom_max_height=&#8217;none&#8217; svg_div_bottom_opacity=&#8221; column_boxshadow_width=&#8217;10&#8217; column_boxshadow_color=&#8221; background=&#8217;bg_color&#8217; background_color=&#8221; background_gradient_direction=&#8217;vertical&#8217; background_gradient_color1=&#8217;#000000&#8242; background_gradient_color2=&#8217;#ffffff&#8217; background_gradient_color3=&#8221; src=&#8221; attachment=&#8221; attachment_size=&#8221; background_position=&#8217;top left&#8217; background_repeat=&#8217;no-repeat&#8217; highlight_size=&#8217;1.1&#8242; animation=&#8221; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; parallax_parallax=&#8221; parallax_parallax_speed=&#8221; av-desktop-parallax_parallax=&#8221; av-desktop-parallax_parallax_speed=&#8221; av-medium-parallax_parallax=&#8221; av-medium-parallax_parallax_speed=&#8221; av-small-parallax_parallax=&#8221; av-small-parallax_parallax_speed=&#8221; av-mini-parallax_parallax=&#8221; av-mini-parallax_parallax_speed=&#8221; css_position=&#8221; css_position_location=&#8217;,,,&#8217; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8217;,,,&#8217; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8217;,,,&#8217; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8217;,,,&#8217; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8217;,,,&#8217; av-mini-css_position_z_index=&#8221; link=&#8221; linktarget=&#8221; link_hover=&#8221; title_attr=&#8221; alt_attr=&#8221; mobile_display=&#8221; mobile_col_pos=&#8217;0&#8242; id=&#8221; custom_class=&#8221; template_class=&#8221; aria_label=&#8221; av_uid=&#8217;av-xu0g86&#8242; sc_version=&#8217;1.0&#8242;]<br \/>\n[av_image src=&#8217;http:\/\/manpro.id\/product\/wp-content\/uploads\/2023\/05\/Window-app-new-03-1-1500&#215;630.png&#8217; attachment=&#8217;5678&#8242; attachment_size=&#8217;featured_large&#8217; copyright=&#8221; caption=&#8221; image_size=&#8217;no scaling&#8217; styling=&#8221; box_shadow=&#8217;none&#8217; box_shadow_width=&#8217;10&#8217; box_shadow_color=&#8221; align=&#8217;center&#8217; font_size=&#8221; overlay_opacity=&#8217;0.4&#8242; overlay_color=&#8217;#000000&#8242; overlay_text_color=&#8217;#ffffff&#8217; link=&#8221; target=&#8221; animation=&#8217;no-animation&#8217; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; parallax_parallax=&#8221; parallax_parallax_speed=&#8221; av-desktop-parallax_parallax=&#8221; av-desktop-parallax_parallax_speed=&#8221; av-medium-parallax_parallax=&#8221; av-medium-parallax_parallax_speed=&#8221; av-small-parallax_parallax=&#8221; av-small-parallax_parallax_speed=&#8221; av-mini-parallax_parallax=&#8221; av-mini-parallax_parallax_speed=&#8221; hover=&#8221; blur_image=&#8221; grayscale_image=&#8221; fade_image=&#8221; appearance=&#8221; css_position=&#8221; css_position_location=&#8217;,,,&#8217; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8217;,,,&#8217; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8217;,,,&#8217; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8217;,,,&#8217; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8217;,,,&#8217; av-mini-css_position_z_index=&#8221; transform_perspective=&#8221; transform_rotation=&#8217;,,,&#8217; transform_scale=&#8217;,,&#8217; transform_skew=&#8217;,&#8217; transform_translate=&#8217;,,&#8217; av-desktop-transform_perspective=&#8221; av-desktop-transform_rotation=&#8217;,,,&#8217; av-desktop-transform_scale=&#8217;,,&#8217; av-desktop-transform_skew=&#8217;,&#8217; av-desktop-transform_translate=&#8217;,,&#8217; av-medium-transform_perspective=&#8221; av-medium-transform_rotation=&#8217;,,,&#8217; av-medium-transform_scale=&#8217;,,&#8217; av-medium-transform_skew=&#8217;,&#8217; av-medium-transform_translate=&#8217;,,&#8217; av-small-transform_perspective=&#8221; av-small-transform_rotation=&#8217;,,,&#8217; av-small-transform_scale=&#8217;,,&#8217; av-small-transform_skew=&#8217;,&#8217; av-small-transform_translate=&#8217;,,&#8217; av-mini-transform_perspective=&#8221; av-mini-transform_rotation=&#8217;,,,&#8217; av-mini-transform_scale=&#8217;,,&#8217; av-mini-transform_skew=&#8217;,&#8217; av-mini-transform_translate=&#8217;,,&#8217; mask_overlay=&#8221; mask_overlay_shape=&#8217;blob&#8217; mask_overlay_size=&#8217;contain&#8217; mask_overlay_scale=&#8217;100%&#8217; mask_overlay_position=&#8217;center center&#8217; mask_overlay_repeat=&#8217;no-repeat&#8217; mask_overlay_rotate=&#8221; mask_overlay_rad_shape=&#8217;circle&#8217; mask_overlay_rad_position=&#8217;center center&#8217; mask_overlay_opacity1=&#8217;0&#8242; mask_overlay_opacity2=&#8217;1&#8242; mask_overlay_opacity3=&#8221; title_attr=&#8221; alt_attr=&#8221; img_scrset=&#8221; lazy_loading=&#8217;disabled&#8217; id=&#8221; custom_class=&#8221; template_class=&#8221; av_element_hidden_in_editor=&#8217;0&#8242; av_uid=&#8217;av-lgyngexs&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;][\/av_image]<br \/>\n[\/av_one_half]<\/p>\n<p>[av_one_half min_height=&#8221; vertical_alignment=&#8217;av-align-top&#8217; space=&#8221; row_boxshadow=&#8221; row_boxshadow_width=&#8217;10&#8217; row_boxshadow_color=&#8221; custom_margin=&#8221; margin=&#8217;0px&#8217; av-desktop-margin=&#8221; av-medium-margin=&#8221; av-small-margin=&#8221; av-mini-margin=&#8221; mobile_breaking=&#8221; mobile_column_order=&#8221; border=&#8221; border_style=&#8217;solid&#8217; border_color=&#8221; radius=&#8221; min_col_height=&#8221; padding=&#8221; av-desktop-padding=&#8221; av-medium-padding=&#8221; av-small-padding=&#8221; av-mini-padding=&#8221; svg_div_top=&#8221; svg_div_top_color=&#8217;#333333&#8242; svg_div_top_width=&#8217;100&#8242; svg_div_top_height=&#8217;50&#8217; svg_div_top_max_height=&#8217;none&#8217; svg_div_top_flip=&#8221; svg_div_top_invert=&#8221; svg_div_top_front=&#8221; svg_div_top_opacity=&#8221; svg_div_top_preview=&#8221; svg_div_bottom=&#8221; svg_div_bottom_color=&#8217;#333333&#8242; svg_div_bottom_width=&#8217;100&#8242; svg_div_bottom_height=&#8217;50&#8217; svg_div_bottom_max_height=&#8217;none&#8217; svg_div_bottom_flip=&#8221; svg_div_bottom_invert=&#8221; svg_div_bottom_front=&#8221; svg_div_bottom_opacity=&#8221; svg_div_bottom_preview=&#8221; column_boxshadow=&#8221; column_boxshadow_width=&#8217;10&#8217; column_boxshadow_color=&#8221; background=&#8217;bg_color&#8217; background_color=&#8221; background_gradient_direction=&#8217;vertical&#8217; background_gradient_color1=&#8217;#000000&#8242; background_gradient_color2=&#8217;#ffffff&#8217; background_gradient_color3=&#8221; src=&#8221; background_position=&#8217;top left&#8217; background_repeat=&#8217;no-repeat&#8217; highlight=&#8221; highlight_size=&#8221; animation=&#8221; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; parallax_parallax=&#8221; parallax_parallax_speed=&#8221; av-desktop-parallax_parallax=&#8221; av-desktop-parallax_parallax_speed=&#8221; av-medium-parallax_parallax=&#8221; av-medium-parallax_parallax_speed=&#8221; av-small-parallax_parallax=&#8221; av-small-parallax_parallax_speed=&#8221; av-mini-parallax_parallax=&#8221; av-mini-parallax_parallax_speed=&#8221; css_position=&#8221; css_position_location=&#8221; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8221; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8221; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8221; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8221; av-mini-css_position_z_index=&#8221; link=&#8221; linktarget=&#8221; link_hover=&#8221; title_attr=&#8221; alt_attr=&#8221; mobile_display=&#8221; mobile_col_pos=&#8217;0&#8242; id=&#8221; custom_class=&#8221; template_class=&#8221; aria_label=&#8221; av_uid=&#8217;av-wc2sja&#8217; sc_version=&#8217;1.0&#8242;]<br \/>\n[av_textblock textblock_styling_align=&#8221; textblock_styling=&#8221; textblock_styling_gap=&#8221; textblock_styling_mobile=&#8221; size=&#8217;18&#8217; av-desktop-font-size=&#8217;18&#8217; av-medium-font-size=&#8217;18&#8217; av-small-font-size=&#8217;18&#8217; av-mini-font-size=&#8217;18&#8217; font_color=&#8217;custom&#8217; color=&#8217;#e8500e&#8217; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-2lxmo6&#8242; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<h3 class=\"judul mobile-hidden ml20\" style=\"max-width: 85%; font-size: 30px; font-weight: 500;\">Customizable Menu<\/h3>\n<p>[\/av_textblock]<\/p>\n<p>[av_textblock textblock_styling_align=&#8221; textblock_styling=&#8221; textblock_styling_gap=&#8221; textblock_styling_mobile=&#8221; size=&#8217;18&#8217; av-desktop-font-size=&#8221; av-medium-font-size=&#8221; av-small-font-size=&#8221; av-mini-font-size=&#8221; font_color=&#8217;custom&#8217; color=&#8217;#717173&#8242; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-lgyniei8&#8242; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<h4 class=\"mobile-hidden\" style=\"line-height: 1.8; letter-spacing: 0.5px;\">Bebas ciptakan berbagai jenis menu dan laporan yang sesuai dengan kebutuhan di perusahaan Anda.<br \/>\nUbah sistem laporan manual Anda menjadi digital yang dapat diakses oleh seluruh tim Anda.<\/h4>\n<p>[\/av_textblock]<\/p>\n<p>[av_iconlist position=&#8217;left&#8217; iconlist_styling=&#8217;av-iconlist-small&#8217; custom_title_size=&#8217;18&#8217; av-desktop-font-size-title=&#8221; av-medium-font-size-title=&#8221; av-small-font-size-title=&#8221; av-mini-font-size-title=&#8221; custom_content_size=&#8217;18&#8217; av-desktop-font-size=&#8221; av-medium-font-size=&#8221; av-small-font-size=&#8221; av-mini-font-size=&#8221; font_color=&#8217;custom&#8217; custom_title=&#8221; custom_content=&#8217;#717173&#8242; color=&#8217;custom&#8217; custom_font=&#8217;#ffffff&#8217; custom_bg=&#8217;#e8500e&#8217; custom_border=&#8221; gradient_color_direction=&#8217;vertical&#8217; gradient_color_1=&#8217;#000000&#8242; gradient_color_2=&#8217;#ffffff&#8217; gradient_color_3=&#8221; border=&#8221; border_width=&#8221; border_width_sync=&#8217;true&#8217; border_color=&#8221; box_shadow=&#8221; box_shadow_style=&#8217;0px,0px,0px,0px&#8217; box_shadow_color=&#8221; animation=&#8221; sonar_effect_effect=&#8221; sonar_effect_color=&#8221; sonar_effect_duration=&#8217;1&#8242; sonar_effect_scale=&#8221; sonar_effect_opac=&#8217;0.5&#8242; alb_description=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-lgynkmyi&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<br \/>\n[av_iconlist_item title=&#8221; icon=&#8217;ue812&#8242; font=&#8217;entypo-fontello&#8217; heading_tag=&#8221; heading_class=&#8221; link=&#8221; linktarget=&#8221; linkelement=&#8221; av_uid=&#8217;av-lgynjbv5&#8242; sc_version=&#8217;1.0&#8242;]<\/p>\n<h4 class=\"mobile-hidden\" style=\"line-height: 1.8; letter-spacing: 0.5px; padding-left: 10px;\">Bebas tentukan aktivitas yang akan Anda monitor<\/h4>\n<p>[\/av_iconlist_item]<br \/>\n[av_iconlist_item title=&#8221; icon=&#8217;ue812&#8242; font=&#8217;entypo-fontello&#8217; heading_tag=&#8221; heading_class=&#8221; link=&#8221; linktarget=&#8221; linkelement=&#8221; av_uid=&#8217;av-lgynjt6b&#8217; sc_version=&#8217;1.0&#8242;]<\/p>\n<h4 class=\"mobile-hidden\" style=\"line-height: 1.8; letter-spacing: 0.5px; padding-left: 10px;\">Dilengkapi dengan target, penugasan dan kategori yang dapat dikustomisasi<\/h4>\n<p>[\/av_iconlist_item]<br \/>\n[av_iconlist_item title=&#8221; icon=&#8217;ue812&#8242; font=&#8217;entypo-fontello&#8217; heading_tag=&#8221; heading_class=&#8221; link=&#8221; linktarget=&#8221; linkelement=&#8221; av_uid=&#8217;av-lgynkl3j&#8217; sc_version=&#8217;1.0&#8242;]<\/p>\n<h4 class=\"mobile-hidden\" style=\"line-height: 1.8; letter-spacing: 0.5px; padding-left: 10px;\">Dilengkapi dengan target, penugasan dan kategori yang dapat dikustomisasi<\/h4>\n<p>[\/av_iconlist_item]<br \/>\n[\/av_iconlist]<br \/>\n[\/av_one_half]<\/p>\n<p>[av_hr class=&#8217;invisible&#8217; icon_select=&#8217;yes&#8217; icon=&#8217;ue808&#8242; font=&#8217;entypo-fontello&#8217; position=&#8217;center&#8217; shadow=&#8217;no-shadow&#8217; height=&#8217;100&#8242; custom_border=&#8217;av-border-thin&#8217; custom_width=&#8217;50px&#8217; custom_margin_top=&#8217;30px&#8217; custom_margin_bottom=&#8217;30px&#8217; custom_border_color=&#8221; custom_icon_color=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-2kim92&#8242; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<p>[av_one_half first min_height=&#8221; vertical_alignment=&#8217;av-align-top&#8217; space=&#8217;no_margin&#8217; row_boxshadow_width=&#8217;10&#8217; row_boxshadow_color=&#8221; margin=&#8217;0px&#8217; margin_sync=&#8217;true&#8217; av-desktop-margin=&#8221; av-desktop-margin_sync=&#8217;true&#8217; av-medium-margin=&#8221; av-medium-margin_sync=&#8217;true&#8217; av-small-margin=&#8221; av-small-margin_sync=&#8217;true&#8217; av-mini-margin=&#8221; av-mini-margin_sync=&#8217;true&#8217; mobile_breaking=&#8221; mobile_column_order=&#8221; border=&#8221; border_style=&#8217;solid&#8217; border_color=&#8221; radius=&#8221; radius_sync=&#8217;true&#8217; min_col_height=&#8221; padding=&#8221; padding_sync=&#8217;true&#8217; av-desktop-padding=&#8221; av-desktop-padding_sync=&#8217;true&#8217; av-medium-padding=&#8221; av-medium-padding_sync=&#8217;true&#8217; av-small-padding=&#8221; av-small-padding_sync=&#8217;true&#8217; av-mini-padding=&#8221; av-mini-padding_sync=&#8217;true&#8217; svg_div_top=&#8221; svg_div_top_color=&#8217;#333333&#8242; svg_div_top_width=&#8217;100&#8242; svg_div_top_height=&#8217;50&#8217; svg_div_top_max_height=&#8217;none&#8217; svg_div_top_opacity=&#8221; svg_div_bottom=&#8221; svg_div_bottom_color=&#8217;#333333&#8242; svg_div_bottom_width=&#8217;100&#8242; svg_div_bottom_height=&#8217;50&#8217; svg_div_bottom_max_height=&#8217;none&#8217; svg_div_bottom_opacity=&#8221; column_boxshadow_width=&#8217;10&#8217; column_boxshadow_color=&#8221; background=&#8217;bg_color&#8217; background_color=&#8221; background_gradient_direction=&#8217;vertical&#8217; background_gradient_color1=&#8217;#000000&#8242; background_gradient_color2=&#8217;#ffffff&#8217; background_gradient_color3=&#8221; src=&#8221; attachment=&#8221; attachment_size=&#8221; background_position=&#8217;top left&#8217; background_repeat=&#8217;no-repeat&#8217; highlight_size=&#8217;1.1&#8242; animation=&#8221; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; parallax_parallax=&#8221; parallax_parallax_speed=&#8221; av-desktop-parallax_parallax=&#8221; av-desktop-parallax_parallax_speed=&#8221; av-medium-parallax_parallax=&#8221; av-medium-parallax_parallax_speed=&#8221; av-small-parallax_parallax=&#8221; av-small-parallax_parallax_speed=&#8221; av-mini-parallax_parallax=&#8221; av-mini-parallax_parallax_speed=&#8221; css_position=&#8221; css_position_location=&#8217;,,,&#8217; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8217;,,,&#8217; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8217;,,,&#8217; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8217;,,,&#8217; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8217;,,,&#8217; av-mini-css_position_z_index=&#8221; link=&#8221; linktarget=&#8221; link_hover=&#8221; title_attr=&#8221; alt_attr=&#8221; mobile_display=&#8221; mobile_col_pos=&#8217;0&#8242; id=&#8221; custom_class=&#8221; template_class=&#8221; aria_label=&#8221; av_uid=&#8217;av-ut975i&#8217; sc_version=&#8217;1.0&#8242;]<br \/>\n[av_textblock textblock_styling_align=&#8221; textblock_styling=&#8221; textblock_styling_gap=&#8221; textblock_styling_mobile=&#8221; size=&#8217;18&#8217; av-desktop-font-size=&#8217;18&#8217; av-medium-font-size=&#8217;18&#8217; av-small-font-size=&#8217;18&#8217; av-mini-font-size=&#8217;18&#8217; font_color=&#8217;custom&#8217; color=&#8217;#e8500e&#8217; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-li9yppnn&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<h3 class=\"judul mobile-hidden ml20\" style=\"max-width: 85%; font-size: 30px; font-weight: 500;\">Unlimited Report Form<\/h3>\n<p>[\/av_textblock]<\/p>\n<p>[av_textblock textblock_styling_align=&#8221; textblock_styling=&#8221; textblock_styling_gap=&#8221; textblock_styling_mobile=&#8221; size=&#8221; av-desktop-font-size=&#8221; av-medium-font-size=&#8221; av-small-font-size=&#8221; av-mini-font-size=&#8221; font_color=&#8217;custom&#8217; color=&#8217;#717173&#8242; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-lgynlslx&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<h4 class=\"mobile-hidden\" style=\"line-height: 1.8; letter-spacing: 0.5px;\">Berbagai bentuk laporan dapat Anda buat untuk menunjang aktivitas di lapangan mulai dari laporan harian, stock material, tenaga kerja, punchlist atau apapun yang dapat Anda pikirkan<\/h4>\n<p>[\/av_textblock]<br \/>\n[\/av_one_half]<\/p>\n<p>[av_one_half min_height=&#8221; vertical_alignment=&#8217;av-align-top&#8217; space=&#8221; row_boxshadow=&#8221; row_boxshadow_width=&#8217;10&#8217; row_boxshadow_color=&#8221; custom_margin=&#8221; margin=&#8217;0px&#8217; av-desktop-margin=&#8221; av-medium-margin=&#8221; av-small-margin=&#8221; av-mini-margin=&#8221; mobile_breaking=&#8221; mobile_column_order=&#8221; border=&#8221; border_style=&#8217;solid&#8217; border_color=&#8221; radius=&#8221; min_col_height=&#8221; padding=&#8221; av-desktop-padding=&#8221; av-medium-padding=&#8221; av-small-padding=&#8221; av-mini-padding=&#8221; svg_div_top=&#8221; svg_div_top_color=&#8217;#333333&#8242; svg_div_top_width=&#8217;100&#8242; svg_div_top_height=&#8217;50&#8217; svg_div_top_max_height=&#8217;none&#8217; svg_div_top_flip=&#8221; svg_div_top_invert=&#8221; svg_div_top_front=&#8221; svg_div_top_opacity=&#8221; svg_div_top_preview=&#8221; svg_div_bottom=&#8221; svg_div_bottom_color=&#8217;#333333&#8242; svg_div_bottom_width=&#8217;100&#8242; svg_div_bottom_height=&#8217;50&#8217; svg_div_bottom_max_height=&#8217;none&#8217; svg_div_bottom_flip=&#8221; svg_div_bottom_invert=&#8221; svg_div_bottom_front=&#8221; svg_div_bottom_opacity=&#8221; svg_div_bottom_preview=&#8221; column_boxshadow=&#8221; column_boxshadow_width=&#8217;10&#8217; column_boxshadow_color=&#8221; background=&#8217;bg_color&#8217; background_color=&#8221; background_gradient_direction=&#8217;vertical&#8217; background_gradient_color1=&#8217;#000000&#8242; background_gradient_color2=&#8217;#ffffff&#8217; background_gradient_color3=&#8221; src=&#8221; background_position=&#8217;top left&#8217; background_repeat=&#8217;no-repeat&#8217; highlight=&#8221; highlight_size=&#8221; animation=&#8221; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; parallax_parallax=&#8221; parallax_parallax_speed=&#8221; av-desktop-parallax_parallax=&#8221; av-desktop-parallax_parallax_speed=&#8221; av-medium-parallax_parallax=&#8221; av-medium-parallax_parallax_speed=&#8221; av-small-parallax_parallax=&#8221; av-small-parallax_parallax_speed=&#8221; av-mini-parallax_parallax=&#8221; av-mini-parallax_parallax_speed=&#8221; css_position=&#8221; css_position_location=&#8221; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8221; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8221; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8221; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8221; av-mini-css_position_z_index=&#8221; link=&#8221; linktarget=&#8221; link_hover=&#8221; title_attr=&#8221; alt_attr=&#8221; mobile_display=&#8221; mobile_col_pos=&#8217;0&#8242; id=&#8221; custom_class=&#8221; template_class=&#8221; aria_label=&#8221; av_uid=&#8217;av-mocsdy&#8217; sc_version=&#8217;1.0&#8242;]<br \/>\n[av_image src=&#8217;http:\/\/manpro.id\/product\/wp-content\/uploads\/2023\/05\/Window-app-new-07-300&#215;150.png&#8217; attachment=&#8217;5169&#8242; attachment_size=&#8217;medium&#8217; copyright=&#8221; caption=&#8221; image_size=&#8217;no scaling&#8217; styling=&#8221; box_shadow=&#8217;none&#8217; box_shadow_width=&#8217;10&#8217; box_shadow_color=&#8221; align=&#8217;center&#8217; font_size=&#8221; overlay_opacity=&#8217;0.4&#8242; overlay_color=&#8217;#000000&#8242; overlay_text_color=&#8217;#ffffff&#8217; link=&#8221; target=&#8221; animation=&#8217;no-animation&#8217; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; parallax_parallax=&#8221; parallax_parallax_speed=&#8221; av-desktop-parallax_parallax=&#8221; av-desktop-parallax_parallax_speed=&#8221; av-medium-parallax_parallax=&#8221; av-medium-parallax_parallax_speed=&#8221; av-small-parallax_parallax=&#8221; av-small-parallax_parallax_speed=&#8221; av-mini-parallax_parallax=&#8221; av-mini-parallax_parallax_speed=&#8221; hover=&#8221; blur_image=&#8221; grayscale_image=&#8221; fade_image=&#8221; appearance=&#8221; css_position=&#8221; css_position_location=&#8217;,,,&#8217; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8217;,,,&#8217; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8217;,,,&#8217; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8217;,,,&#8217; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8217;,,,&#8217; av-mini-css_position_z_index=&#8221; transform_perspective=&#8221; transform_rotation=&#8217;,,,&#8217; transform_scale=&#8217;,,&#8217; transform_skew=&#8217;,&#8217; transform_translate=&#8217;,,&#8217; av-desktop-transform_perspective=&#8221; av-desktop-transform_rotation=&#8217;,,,&#8217; av-desktop-transform_scale=&#8217;,,&#8217; av-desktop-transform_skew=&#8217;,&#8217; av-desktop-transform_translate=&#8217;,,&#8217; av-medium-transform_perspective=&#8221; av-medium-transform_rotation=&#8217;,,,&#8217; av-medium-transform_scale=&#8217;,,&#8217; av-medium-transform_skew=&#8217;,&#8217; av-medium-transform_translate=&#8217;,,&#8217; av-small-transform_perspective=&#8221; av-small-transform_rotation=&#8217;,,,&#8217; av-small-transform_scale=&#8217;,,&#8217; av-small-transform_skew=&#8217;,&#8217; av-small-transform_translate=&#8217;,,&#8217; av-mini-transform_perspective=&#8221; av-mini-transform_rotation=&#8217;,,,&#8217; av-mini-transform_scale=&#8217;,,&#8217; av-mini-transform_skew=&#8217;,&#8217; av-mini-transform_translate=&#8217;,,&#8217; mask_overlay=&#8221; mask_overlay_shape=&#8217;blob&#8217; mask_overlay_size=&#8217;contain&#8217; mask_overlay_scale=&#8217;100%&#8217; mask_overlay_position=&#8217;center center&#8217; mask_overlay_repeat=&#8217;no-repeat&#8217; mask_overlay_rotate=&#8221; mask_overlay_rad_shape=&#8217;circle&#8217; mask_overlay_rad_position=&#8217;center center&#8217; mask_overlay_opacity1=&#8217;0&#8242; mask_overlay_opacity2=&#8217;1&#8242; mask_overlay_opacity3=&#8221; title_attr=&#8221; alt_attr=&#8221; img_scrset=&#8221; lazy_loading=&#8217;disabled&#8217; id=&#8221; custom_class=&#8221; template_class=&#8221; av_element_hidden_in_editor=&#8217;0&#8242; av_uid=&#8217;av-lgyngw8w&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;][\/av_image]<br \/>\n[\/av_one_half]<\/p>\n<p>[av_hr class=&#8217;invisible&#8217; icon_select=&#8217;yes&#8217; icon=&#8217;ue808&#8242; font=&#8217;entypo-fontello&#8217; position=&#8217;center&#8217; shadow=&#8217;no-shadow&#8217; height=&#8217;100&#8242; custom_border=&#8217;av-border-thin&#8217; custom_width=&#8217;50px&#8217; custom_margin_top=&#8217;30px&#8217; custom_margin_bottom=&#8217;30px&#8217; custom_border_color=&#8221; custom_icon_color=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-lhkk27ie&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<p>[av_one_half first min_height=&#8221; vertical_alignment=&#8217;av-align-top&#8217; space=&#8217;no_margin&#8217; row_boxshadow_width=&#8217;10&#8217; row_boxshadow_color=&#8221; margin=&#8217;0px&#8217; margin_sync=&#8217;true&#8217; av-desktop-margin=&#8221; av-desktop-margin_sync=&#8217;true&#8217; av-medium-margin=&#8221; av-medium-margin_sync=&#8217;true&#8217; av-small-margin=&#8221; av-small-margin_sync=&#8217;true&#8217; av-mini-margin=&#8221; av-mini-margin_sync=&#8217;true&#8217; mobile_breaking=&#8221; mobile_column_order=&#8221; border=&#8221; border_style=&#8217;solid&#8217; border_color=&#8221; radius=&#8221; radius_sync=&#8217;true&#8217; min_col_height=&#8221; padding=&#8221; padding_sync=&#8217;true&#8217; av-desktop-padding=&#8221; av-desktop-padding_sync=&#8217;true&#8217; av-medium-padding=&#8221; av-medium-padding_sync=&#8217;true&#8217; av-small-padding=&#8221; av-small-padding_sync=&#8217;true&#8217; av-mini-padding=&#8221; av-mini-padding_sync=&#8217;true&#8217; svg_div_top=&#8221; svg_div_top_color=&#8217;#333333&#8242; svg_div_top_width=&#8217;100&#8242; svg_div_top_height=&#8217;50&#8217; svg_div_top_max_height=&#8217;none&#8217; svg_div_top_opacity=&#8221; svg_div_bottom=&#8221; svg_div_bottom_color=&#8217;#333333&#8242; svg_div_bottom_width=&#8217;100&#8242; svg_div_bottom_height=&#8217;50&#8217; svg_div_bottom_max_height=&#8217;none&#8217; svg_div_bottom_opacity=&#8221; column_boxshadow_width=&#8217;10&#8217; column_boxshadow_color=&#8221; background=&#8217;bg_color&#8217; background_color=&#8221; background_gradient_direction=&#8217;vertical&#8217; background_gradient_color1=&#8217;#000000&#8242; background_gradient_color2=&#8217;#ffffff&#8217; background_gradient_color3=&#8221; src=&#8221; attachment=&#8221; attachment_size=&#8221; background_position=&#8217;top left&#8217; background_repeat=&#8217;no-repeat&#8217; highlight_size=&#8217;1.1&#8242; animation=&#8221; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; parallax_parallax=&#8221; parallax_parallax_speed=&#8221; av-desktop-parallax_parallax=&#8221; av-desktop-parallax_parallax_speed=&#8221; av-medium-parallax_parallax=&#8221; av-medium-parallax_parallax_speed=&#8221; av-small-parallax_parallax=&#8221; av-small-parallax_parallax_speed=&#8221; av-mini-parallax_parallax=&#8221; av-mini-parallax_parallax_speed=&#8221; css_position=&#8221; css_position_location=&#8217;,,,&#8217; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8217;,,,&#8217; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8217;,,,&#8217; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8217;,,,&#8217; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8217;,,,&#8217; av-mini-css_position_z_index=&#8221; link=&#8221; linktarget=&#8221; link_hover=&#8221; title_attr=&#8221; alt_attr=&#8221; mobile_display=&#8221; mobile_col_pos=&#8217;0&#8242; id=&#8221; custom_class=&#8221; template_class=&#8221; aria_label=&#8221; av_uid=&#8217;av-km53ty&#8217; sc_version=&#8217;1.0&#8242;]<br \/>\n[av_image src=&#8217;http:\/\/manpro.id\/product\/wp-content\/uploads\/2023\/05\/Window-app-new-20-300&#215;150.png&#8217; attachment=&#8217;5210&#8242; attachment_size=&#8217;medium&#8217; copyright=&#8221; caption=&#8221; image_size=&#8217;no scaling&#8217; styling=&#8221; box_shadow=&#8217;none&#8217; box_shadow_width=&#8217;10&#8217; box_shadow_color=&#8221; align=&#8217;center&#8217; font_size=&#8221; overlay_opacity=&#8217;0.4&#8242; overlay_color=&#8217;#000000&#8242; overlay_text_color=&#8217;#ffffff&#8217; link=&#8221; target=&#8221; animation=&#8217;no-animation&#8217; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; parallax_parallax=&#8221; parallax_parallax_speed=&#8221; av-desktop-parallax_parallax=&#8221; av-desktop-parallax_parallax_speed=&#8221; av-medium-parallax_parallax=&#8221; av-medium-parallax_parallax_speed=&#8221; av-small-parallax_parallax=&#8221; av-small-parallax_parallax_speed=&#8221; av-mini-parallax_parallax=&#8221; av-mini-parallax_parallax_speed=&#8221; hover=&#8221; blur_image=&#8221; grayscale_image=&#8221; fade_image=&#8221; appearance=&#8221; css_position=&#8221; css_position_location=&#8217;,,,&#8217; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8217;,,,&#8217; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8217;,,,&#8217; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8217;,,,&#8217; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8217;,,,&#8217; av-mini-css_position_z_index=&#8221; transform_perspective=&#8221; transform_rotation=&#8217;,,,&#8217; transform_scale=&#8217;,,&#8217; transform_skew=&#8217;,&#8217; transform_translate=&#8217;,,&#8217; av-desktop-transform_perspective=&#8221; av-desktop-transform_rotation=&#8217;,,,&#8217; av-desktop-transform_scale=&#8217;,,&#8217; av-desktop-transform_skew=&#8217;,&#8217; av-desktop-transform_translate=&#8217;,,&#8217; av-medium-transform_perspective=&#8221; av-medium-transform_rotation=&#8217;,,,&#8217; av-medium-transform_scale=&#8217;,,&#8217; av-medium-transform_skew=&#8217;,&#8217; av-medium-transform_translate=&#8217;,,&#8217; av-small-transform_perspective=&#8221; av-small-transform_rotation=&#8217;,,,&#8217; av-small-transform_scale=&#8217;,,&#8217; av-small-transform_skew=&#8217;,&#8217; av-small-transform_translate=&#8217;,,&#8217; av-mini-transform_perspective=&#8221; av-mini-transform_rotation=&#8217;,,,&#8217; av-mini-transform_scale=&#8217;,,&#8217; av-mini-transform_skew=&#8217;,&#8217; av-mini-transform_translate=&#8217;,,&#8217; mask_overlay=&#8221; mask_overlay_shape=&#8217;blob&#8217; mask_overlay_size=&#8217;contain&#8217; mask_overlay_scale=&#8217;100%&#8217; mask_overlay_position=&#8217;center center&#8217; mask_overlay_repeat=&#8217;no-repeat&#8217; mask_overlay_rotate=&#8221; mask_overlay_rad_shape=&#8217;circle&#8217; mask_overlay_rad_position=&#8217;center center&#8217; mask_overlay_opacity1=&#8217;0&#8242; mask_overlay_opacity2=&#8217;1&#8242; mask_overlay_opacity3=&#8221; title_attr=&#8221; alt_attr=&#8221; img_scrset=&#8221; lazy_loading=&#8217;disabled&#8217; id=&#8221; custom_class=&#8221; template_class=&#8221; av_element_hidden_in_editor=&#8217;0&#8242; av_uid=&#8217;av-lhm5nfs7&#8242; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;][\/av_image]<br \/>\n[\/av_one_half]<\/p>\n<p>[av_one_half min_height=&#8221; vertical_alignment=&#8217;av-align-top&#8217; space=&#8221; row_boxshadow=&#8221; row_boxshadow_width=&#8217;10&#8217; row_boxshadow_color=&#8221; custom_margin=&#8221; margin=&#8217;0px&#8217; av-desktop-margin=&#8221; av-medium-margin=&#8221; av-small-margin=&#8221; av-mini-margin=&#8221; mobile_breaking=&#8221; mobile_column_order=&#8221; border=&#8221; border_style=&#8217;solid&#8217; border_color=&#8221; radius=&#8221; min_col_height=&#8221; padding=&#8221; av-desktop-padding=&#8221; av-medium-padding=&#8221; av-small-padding=&#8221; av-mini-padding=&#8221; svg_div_top=&#8221; svg_div_top_color=&#8217;#333333&#8242; svg_div_top_width=&#8217;100&#8242; svg_div_top_height=&#8217;50&#8217; svg_div_top_max_height=&#8217;none&#8217; svg_div_top_flip=&#8221; svg_div_top_invert=&#8221; svg_div_top_front=&#8221; svg_div_top_opacity=&#8221; svg_div_top_preview=&#8221; svg_div_bottom=&#8221; svg_div_bottom_color=&#8217;#333333&#8242; svg_div_bottom_width=&#8217;100&#8242; svg_div_bottom_height=&#8217;50&#8217; svg_div_bottom_max_height=&#8217;none&#8217; svg_div_bottom_flip=&#8221; svg_div_bottom_invert=&#8221; svg_div_bottom_front=&#8221; svg_div_bottom_opacity=&#8221; svg_div_bottom_preview=&#8221; column_boxshadow=&#8221; column_boxshadow_width=&#8217;10&#8217; column_boxshadow_color=&#8221; background=&#8217;bg_color&#8217; background_color=&#8221; background_gradient_direction=&#8217;vertical&#8217; background_gradient_color1=&#8217;#000000&#8242; background_gradient_color2=&#8217;#ffffff&#8217; background_gradient_color3=&#8221; src=&#8221; background_position=&#8217;top left&#8217; background_repeat=&#8217;no-repeat&#8217; highlight=&#8221; highlight_size=&#8221; animation=&#8221; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; parallax_parallax=&#8221; parallax_parallax_speed=&#8221; av-desktop-parallax_parallax=&#8221; av-desktop-parallax_parallax_speed=&#8221; av-medium-parallax_parallax=&#8221; av-medium-parallax_parallax_speed=&#8221; av-small-parallax_parallax=&#8221; av-small-parallax_parallax_speed=&#8221; av-mini-parallax_parallax=&#8221; av-mini-parallax_parallax_speed=&#8221; css_position=&#8221; css_position_location=&#8221; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8221; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8221; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8221; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8221; av-mini-css_position_z_index=&#8221; link=&#8221; linktarget=&#8221; link_hover=&#8221; title_attr=&#8221; alt_attr=&#8221; mobile_display=&#8221; mobile_col_pos=&#8217;0&#8242; id=&#8221; custom_class=&#8221; template_class=&#8221; aria_label=&#8221; av_uid=&#8217;av-1uxeo6&#8242; sc_version=&#8217;1.0&#8242;]<br \/>\n[av_textblock textblock_styling_align=&#8221; textblock_styling=&#8221; textblock_styling_gap=&#8221; textblock_styling_mobile=&#8221; size=&#8217;18&#8217; av-desktop-font-size=&#8217;18&#8217; av-medium-font-size=&#8217;18&#8217; av-small-font-size=&#8217;18&#8217; av-mini-font-size=&#8217;18&#8217; font_color=&#8217;custom&#8217; color=&#8217;#e8500e&#8217; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-4wyb9i&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<h3 class=\"judul mobile-hidden ml20\" style=\"max-width: 85%; font-size: 30px; font-weight: 500;\">Printable &amp; Downloadable Report<\/h3>\n<p>[\/av_textblock]<\/p>\n<p>[av_textblock textblock_styling_align=&#8221; textblock_styling=&#8221; textblock_styling_gap=&#8221; textblock_styling_mobile=&#8221; size=&#8221; av-desktop-font-size=&#8221; av-medium-font-size=&#8221; av-small-font-size=&#8221; av-mini-font-size=&#8221; font_color=&#8217;custom&#8217; color=&#8217;#717173&#8242; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-lhm4w0o6&#8242; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<h4 class=\"mobile-hidden\" style=\"line-height: 1.8; letter-spacing: 0.5px;\">Seluruh data yang terinput dapat diunduh &amp; print ulang dalam bentuk hardcopy sesuai dengan format yang Anda dalam laporan tersebut<\/h4>\n<p>[\/av_textblock]<\/p>\n<p>[av_iconlist position=&#8217;left&#8217; iconlist_styling=&#8217;av-iconlist-small&#8217; custom_title_size=&#8221; av-desktop-font-size-title=&#8221; av-medium-font-size-title=&#8221; av-small-font-size-title=&#8221; av-mini-font-size-title=&#8221; custom_content_size=&#8221; av-desktop-font-size=&#8221; av-medium-font-size=&#8221; av-small-font-size=&#8221; av-mini-font-size=&#8221; font_color=&#8217;custom&#8217; custom_title=&#8217;#717173&#8242; custom_content=&#8217;#717173&#8242; color=&#8217;custom&#8217; custom_font=&#8217;#ffffff&#8217; custom_bg=&#8217;#e8500e&#8217; custom_border=&#8221; gradient_color_direction=&#8217;vertical&#8217; gradient_color_1=&#8217;#000000&#8242; gradient_color_2=&#8217;#ffffff&#8217; gradient_color_3=&#8221; border=&#8221; border_width=&#8221; border_width_sync=&#8217;true&#8217; border_color=&#8221; box_shadow=&#8221; box_shadow_style=&#8217;0px,0px,0px,0px&#8217; box_shadow_color=&#8221; animation=&#8221; sonar_effect_effect=&#8221; sonar_effect_color=&#8221; sonar_effect_duration=&#8217;1&#8242; sonar_effect_scale=&#8221; sonar_effect_opac=&#8217;0.5&#8242; alb_description=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-hxvbba&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<br \/>\n[av_iconlist_item title=&#8221; icon=&#8217;ue812&#8242; font=&#8217;entypo-fontello&#8217; heading_tag=&#8221; heading_class=&#8221; link=&#8221; linktarget=&#8221; linkelement=&#8221; av_uid=&#8217;av-g0cyfq&#8217; sc_version=&#8217;1.0&#8242;]<\/p>\n<h4 class=\"mobile-hidden\" style=\"line-height: 1.8; letter-spacing: 0.5px; padding-left: 10px;\">Printout custom PDF sesuai bentuk laporan<\/h4>\n<p>[\/av_iconlist_item]<br \/>\n[av_iconlist_item title=&#8221; icon=&#8217;ue812&#8242; font=&#8217;entypo-fontello&#8217; heading_tag=&#8221; heading_class=&#8221; link=&#8221; linktarget=&#8221; linkelement=&#8221; av_uid=&#8217;av-dqu2km&#8217; sc_version=&#8217;1.0&#8242;]<\/p>\n<h4 class=\"mobile-hidden\" style=\"line-height: 1.8; letter-spacing: 0.5px; padding-left: 10px;\">Export data to XLS \/ PDF untuk analisa lebih lanjut<\/h4>\n<p>[\/av_iconlist_item]<br \/>\n[\/av_iconlist]<br \/>\n[\/av_one_half]<\/p>\n<p>[av_hr class=&#8217;invisible&#8217; icon_select=&#8217;yes&#8217; icon=&#8217;ue808&#8242; font=&#8217;entypo-fontello&#8217; position=&#8217;center&#8217; shadow=&#8217;no-shadow&#8217; height=&#8217;100&#8242; custom_border=&#8217;av-border-thin&#8217; custom_width=&#8217;50px&#8217; custom_margin_top=&#8217;30px&#8217; custom_margin_bottom=&#8217;30px&#8217; custom_border_color=&#8221; custom_icon_color=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-lhkk2pm9&#8242; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<p>[av_one_half first min_height=&#8221; vertical_alignment=&#8217;av-align-top&#8217; space=&#8217;no_margin&#8217; row_boxshadow_width=&#8217;10&#8217; row_boxshadow_color=&#8221; margin=&#8217;0px&#8217; margin_sync=&#8217;true&#8217; av-desktop-margin=&#8221; av-desktop-margin_sync=&#8217;true&#8217; av-medium-margin=&#8221; av-medium-margin_sync=&#8217;true&#8217; av-small-margin=&#8221; av-small-margin_sync=&#8217;true&#8217; av-mini-margin=&#8221; av-mini-margin_sync=&#8217;true&#8217; mobile_breaking=&#8221; mobile_column_order=&#8221; border=&#8221; border_style=&#8217;solid&#8217; border_color=&#8221; radius=&#8221; radius_sync=&#8217;true&#8217; min_col_height=&#8221; padding=&#8221; padding_sync=&#8217;true&#8217; av-desktop-padding=&#8221; av-desktop-padding_sync=&#8217;true&#8217; av-medium-padding=&#8221; av-medium-padding_sync=&#8217;true&#8217; av-small-padding=&#8221; av-small-padding_sync=&#8217;true&#8217; av-mini-padding=&#8221; av-mini-padding_sync=&#8217;true&#8217; svg_div_top=&#8221; svg_div_top_color=&#8217;#333333&#8242; svg_div_top_width=&#8217;100&#8242; svg_div_top_height=&#8217;50&#8217; svg_div_top_max_height=&#8217;none&#8217; svg_div_top_opacity=&#8221; svg_div_bottom=&#8221; svg_div_bottom_color=&#8217;#333333&#8242; svg_div_bottom_width=&#8217;100&#8242; svg_div_bottom_height=&#8217;50&#8217; svg_div_bottom_max_height=&#8217;none&#8217; svg_div_bottom_opacity=&#8221; column_boxshadow_width=&#8217;10&#8217; column_boxshadow_color=&#8221; background=&#8217;bg_color&#8217; background_color=&#8221; background_gradient_direction=&#8217;vertical&#8217; background_gradient_color1=&#8217;#000000&#8242; background_gradient_color2=&#8217;#ffffff&#8217; background_gradient_color3=&#8221; src=&#8221; attachment=&#8221; attachment_size=&#8221; background_position=&#8217;top left&#8217; background_repeat=&#8217;no-repeat&#8217; highlight_size=&#8217;1.1&#8242; animation=&#8221; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; parallax_parallax=&#8221; parallax_parallax_speed=&#8221; av-desktop-parallax_parallax=&#8221; av-desktop-parallax_parallax_speed=&#8221; av-medium-parallax_parallax=&#8221; av-medium-parallax_parallax_speed=&#8221; av-small-parallax_parallax=&#8221; av-small-parallax_parallax_speed=&#8221; av-mini-parallax_parallax=&#8221; av-mini-parallax_parallax_speed=&#8221; css_position=&#8221; css_position_location=&#8217;,,,&#8217; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8217;,,,&#8217; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8217;,,,&#8217; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8217;,,,&#8217; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8217;,,,&#8217; av-mini-css_position_z_index=&#8221; link=&#8221; linktarget=&#8221; link_hover=&#8221; title_attr=&#8221; alt_attr=&#8221; mobile_display=&#8221; mobile_col_pos=&#8217;0&#8242; id=&#8221; custom_class=&#8221; template_class=&#8221; aria_label=&#8221; av_uid=&#8217;av-a8q8xi&#8217; sc_version=&#8217;1.0&#8242;]<br \/>\n[av_textblock textblock_styling_align=&#8221; textblock_styling=&#8221; textblock_styling_gap=&#8221; textblock_styling_mobile=&#8221; size=&#8217;18&#8217; av-desktop-font-size=&#8217;18&#8217; av-medium-font-size=&#8217;18&#8217; av-small-font-size=&#8217;18&#8217; av-mini-font-size=&#8217;18&#8217; font_color=&#8217;custom&#8217; color=&#8217;#e8500e&#8217; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-2b4tra&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<h3 class=\"judul mobile-hidden ml20\" style=\"max-width: 85%; font-size: 30px; font-weight: 500;\">Checklist Items<\/h3>\n<p>[\/av_textblock]<\/p>\n<p>[av_textblock textblock_styling_align=&#8221; textblock_styling=&#8221; textblock_styling_gap=&#8221; textblock_styling_mobile=&#8221; size=&#8221; av-desktop-font-size=&#8221; av-medium-font-size=&#8221; av-small-font-size=&#8221; av-mini-font-size=&#8221; font_color=&#8217;custom&#8217; color=&#8217;#717173&#8242; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-97m32u&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<h4 class=\"mobile-hidden\" style=\"line-height: 1.8; letter-spacing: 0.5px;\">Gunakan fitur checklist untuk memastikan setiap hasil pekerjaan proyek Anda sesuai dengan standard yang sudah ditetapkan.<\/h4>\n<p>[\/av_textblock]<\/p>\n<p>[av_iconlist position=&#8217;left&#8217; iconlist_styling=&#8217;av-iconlist-small&#8217; custom_title_size=&#8221; av-desktop-font-size-title=&#8221; av-medium-font-size-title=&#8221; av-small-font-size-title=&#8221; av-mini-font-size-title=&#8221; custom_content_size=&#8221; av-desktop-font-size=&#8221; av-medium-font-size=&#8221; av-small-font-size=&#8221; av-mini-font-size=&#8221; font_color=&#8217;custom&#8217; custom_title=&#8217;#717173&#8242; custom_content=&#8217;#717173&#8242; color=&#8217;custom&#8217; custom_font=&#8217;#ffffff&#8217; custom_bg=&#8217;#e8500e&#8217; custom_border=&#8221; gradient_color_direction=&#8217;vertical&#8217; gradient_color_1=&#8217;#000000&#8242; gradient_color_2=&#8217;#ffffff&#8217; gradient_color_3=&#8221; border=&#8221; border_width=&#8221; border_width_sync=&#8217;true&#8217; border_color=&#8221; box_shadow=&#8221; box_shadow_style=&#8217;0px,0px,0px,0px&#8217; box_shadow_color=&#8221; animation=&#8221; sonar_effect_effect=&#8221; sonar_effect_color=&#8221; sonar_effect_duration=&#8217;1&#8242; sonar_effect_scale=&#8221; sonar_effect_opac=&#8217;0.5&#8242; alb_description=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-9lhwwm&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<br \/>\n[av_iconlist_item title=&#8221; icon=&#8217;ue812&#8242; font=&#8217;entypo-fontello&#8217; heading_tag=&#8221; heading_class=&#8221; link=&#8221; linktarget=&#8221; linkelement=&#8221; av_uid=&#8217;av-737bau&#8217; sc_version=&#8217;1.0&#8242;]<\/p>\n<h4 class=\"mobile-hidden\" style=\"line-height: 1.8; letter-spacing: 0.5px; padding-left: 10px;\">Gunakan checklist untuk memeriksa hasil pekerjaan lapangan dan standardisasi mutu<\/h4>\n<p>[\/av_iconlist_item]<br \/>\n[av_iconlist_item title=&#8221; icon=&#8217;ue812&#8242; font=&#8217;entypo-fontello&#8217; heading_tag=&#8221; heading_class=&#8221; link=&#8221; linktarget=&#8221; linkelement=&#8221; av_uid=&#8217;av-5n3vva&#8217; sc_version=&#8217;1.0&#8242;]<\/p>\n<h4 class=\"mobile-hidden\" style=\"line-height: 1.8; letter-spacing: 0.5px; padding-left: 10px;\">Kombinasikan dengan alur kerja pengajuan dan persetujuan untuk pemeriksaan lebih mendetil<\/h4>\n<p>[\/av_iconlist_item]<br \/>\n[\/av_iconlist]<br \/>\n[\/av_one_half]<\/p>\n<p>[av_one_half min_height=&#8221; vertical_alignment=&#8217;av-align-top&#8217; space=&#8221; row_boxshadow=&#8221; row_boxshadow_width=&#8217;10&#8217; row_boxshadow_color=&#8221; custom_margin=&#8221; margin=&#8217;0px&#8217; av-desktop-margin=&#8221; av-medium-margin=&#8221; av-small-margin=&#8221; av-mini-margin=&#8221; mobile_breaking=&#8221; mobile_column_order=&#8221; border=&#8221; border_style=&#8217;solid&#8217; border_color=&#8221; radius=&#8221; min_col_height=&#8221; padding=&#8221; av-desktop-padding=&#8221; av-medium-padding=&#8221; av-small-padding=&#8221; av-mini-padding=&#8221; svg_div_top=&#8221; svg_div_top_color=&#8217;#333333&#8242; svg_div_top_width=&#8217;100&#8242; svg_div_top_height=&#8217;50&#8217; svg_div_top_max_height=&#8217;none&#8217; svg_div_top_flip=&#8221; svg_div_top_invert=&#8221; svg_div_top_front=&#8221; svg_div_top_opacity=&#8221; svg_div_top_preview=&#8221; svg_div_bottom=&#8221; svg_div_bottom_color=&#8217;#333333&#8242; svg_div_bottom_width=&#8217;100&#8242; svg_div_bottom_height=&#8217;50&#8217; svg_div_bottom_max_height=&#8217;none&#8217; svg_div_bottom_flip=&#8221; svg_div_bottom_invert=&#8221; svg_div_bottom_front=&#8221; svg_div_bottom_opacity=&#8221; svg_div_bottom_preview=&#8221; column_boxshadow=&#8221; column_boxshadow_width=&#8217;10&#8217; column_boxshadow_color=&#8221; background=&#8217;bg_color&#8217; background_color=&#8221; background_gradient_direction=&#8217;vertical&#8217; background_gradient_color1=&#8217;#000000&#8242; background_gradient_color2=&#8217;#ffffff&#8217; background_gradient_color3=&#8221; src=&#8221; background_position=&#8217;top left&#8217; background_repeat=&#8217;no-repeat&#8217; highlight=&#8221; highlight_size=&#8221; animation=&#8221; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; parallax_parallax=&#8221; parallax_parallax_speed=&#8221; av-desktop-parallax_parallax=&#8221; av-desktop-parallax_parallax_speed=&#8221; av-medium-parallax_parallax=&#8221; av-medium-parallax_parallax_speed=&#8221; av-small-parallax_parallax=&#8221; av-small-parallax_parallax_speed=&#8221; av-mini-parallax_parallax=&#8221; av-mini-parallax_parallax_speed=&#8221; css_position=&#8221; css_position_location=&#8221; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8221; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8221; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8221; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8221; av-mini-css_position_z_index=&#8221; link=&#8221; linktarget=&#8221; link_hover=&#8221; title_attr=&#8221; alt_attr=&#8221; mobile_display=&#8221; mobile_col_pos=&#8217;0&#8242; id=&#8221; custom_class=&#8221; template_class=&#8221; aria_label=&#8221; av_uid=&#8217;av-2zalhi&#8217; sc_version=&#8217;1.0&#8242;]<br \/>\n[av_image src=&#8217;http:\/\/manpro.id\/product\/wp-content\/uploads\/2023\/05\/Window-app-new-25-495&#215;400.png&#8217; attachment=&#8217;5329&#8242; attachment_size=&#8217;portfolio&#8217; copyright=&#8221; caption=&#8221; image_size=&#8217;no scaling&#8217; styling=&#8221; box_shadow=&#8217;none&#8217; box_shadow_width=&#8217;10&#8217; box_shadow_color=&#8221; align=&#8217;center&#8217; font_size=&#8221; overlay_opacity=&#8217;0.4&#8242; overlay_color=&#8217;#000000&#8242; overlay_text_color=&#8217;#ffffff&#8217; link=&#8221; target=&#8221; animation=&#8217;no-animation&#8217; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; parallax_parallax=&#8221; parallax_parallax_speed=&#8221; av-desktop-parallax_parallax=&#8221; av-desktop-parallax_parallax_speed=&#8221; av-medium-parallax_parallax=&#8221; av-medium-parallax_parallax_speed=&#8221; av-small-parallax_parallax=&#8221; av-small-parallax_parallax_speed=&#8221; av-mini-parallax_parallax=&#8221; av-mini-parallax_parallax_speed=&#8221; hover=&#8221; blur_image=&#8221; grayscale_image=&#8221; fade_image=&#8221; appearance=&#8221; css_position=&#8221; css_position_location=&#8217;,,,&#8217; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8217;,,,&#8217; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8217;,,,&#8217; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8217;,,,&#8217; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8217;,,,&#8217; av-mini-css_position_z_index=&#8221; transform_perspective=&#8221; transform_rotation=&#8217;,,,&#8217; transform_scale=&#8217;,,&#8217; transform_skew=&#8217;,&#8217; transform_translate=&#8217;,,&#8217; av-desktop-transform_perspective=&#8221; av-desktop-transform_rotation=&#8217;,,,&#8217; av-desktop-transform_scale=&#8217;,,&#8217; av-desktop-transform_skew=&#8217;,&#8217; av-desktop-transform_translate=&#8217;,,&#8217; av-medium-transform_perspective=&#8221; av-medium-transform_rotation=&#8217;,,,&#8217; av-medium-transform_scale=&#8217;,,&#8217; av-medium-transform_skew=&#8217;,&#8217; av-medium-transform_translate=&#8217;,,&#8217; av-small-transform_perspective=&#8221; av-small-transform_rotation=&#8217;,,,&#8217; av-small-transform_scale=&#8217;,,&#8217; av-small-transform_skew=&#8217;,&#8217; av-small-transform_translate=&#8217;,,&#8217; av-mini-transform_perspective=&#8221; av-mini-transform_rotation=&#8217;,,,&#8217; av-mini-transform_scale=&#8217;,,&#8217; av-mini-transform_skew=&#8217;,&#8217; av-mini-transform_translate=&#8217;,,&#8217; mask_overlay=&#8221; mask_overlay_shape=&#8217;blob&#8217; mask_overlay_size=&#8217;contain&#8217; mask_overlay_scale=&#8217;100%&#8217; mask_overlay_position=&#8217;center center&#8217; mask_overlay_repeat=&#8217;no-repeat&#8217; mask_overlay_rotate=&#8221; mask_overlay_rad_shape=&#8217;circle&#8217; mask_overlay_rad_position=&#8217;center center&#8217; mask_overlay_opacity1=&#8217;0&#8242; mask_overlay_opacity2=&#8217;1&#8242; mask_overlay_opacity3=&#8221; title_attr=&#8221; alt_attr=&#8221; img_scrset=&#8221; lazy_loading=&#8217;disabled&#8217; id=&#8221; custom_class=&#8221; template_class=&#8221; av_element_hidden_in_editor=&#8217;0&#8242; av_uid=&#8217;av-lhikwl7i&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;][\/av_image]<\/p>\n<p>[av_font_icon icon=&#8221; style=&#8221; caption=&#8221; size=&#8217;40px&#8217; position=&#8217;left&#8217; color=&#8221; link=&#8221; linktarget=&#8221; sonar_effect_effect=&#8221; sonar_effect_color=&#8221; sonar_effect_duration=&#8217;1&#8242; sonar_effect_scale=&#8221; sonar_effect_opac=&#8217;0.5&#8242; animation=&#8221; av-desktop-hide=&#8221; av-medium-hide=&#8221; av-small-hide=&#8221; av-mini-hide=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-zanau&#8217; sc_version=&#8217;1.0&#8242;][\/av_font_icon]<br \/>\n[\/av_one_half]<\/p>\n<p>[av_hr class=&#8217;invisible&#8217; icon_select=&#8217;yes&#8217; icon=&#8217;ue808&#8242; font=&#8217;entypo-fontello&#8217; position=&#8217;center&#8217; shadow=&#8217;no-shadow&#8217; height=&#8217;100&#8242; custom_border=&#8217;av-border-thin&#8217; custom_width=&#8217;50px&#8217; custom_margin_top=&#8217;30px&#8217; custom_margin_bottom=&#8217;30px&#8217; custom_border_color=&#8221; custom_icon_color=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-2c3rh2&#8242; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<p>[av_one_half first min_height=&#8221; vertical_alignment=&#8217;av-align-top&#8217; space=&#8217;no_margin&#8217; row_boxshadow_width=&#8217;10&#8217; row_boxshadow_color=&#8221; margin=&#8217;0px&#8217; margin_sync=&#8217;true&#8217; av-desktop-margin=&#8221; av-desktop-margin_sync=&#8217;true&#8217; av-medium-margin=&#8221; av-medium-margin_sync=&#8217;true&#8217; av-small-margin=&#8221; av-small-margin_sync=&#8217;true&#8217; av-mini-margin=&#8221; av-mini-margin_sync=&#8217;true&#8217; mobile_breaking=&#8221; mobile_column_order=&#8221; border=&#8221; border_style=&#8217;solid&#8217; border_color=&#8221; radius=&#8221; radius_sync=&#8217;true&#8217; min_col_height=&#8221; padding=&#8221; padding_sync=&#8217;true&#8217; av-desktop-padding=&#8221; av-desktop-padding_sync=&#8217;true&#8217; av-medium-padding=&#8221; av-medium-padding_sync=&#8217;true&#8217; av-small-padding=&#8221; av-small-padding_sync=&#8217;true&#8217; av-mini-padding=&#8221; av-mini-padding_sync=&#8217;true&#8217; svg_div_top=&#8221; svg_div_top_color=&#8217;#333333&#8242; svg_div_top_width=&#8217;100&#8242; svg_div_top_height=&#8217;50&#8217; svg_div_top_max_height=&#8217;none&#8217; svg_div_top_opacity=&#8221; svg_div_bottom=&#8221; svg_div_bottom_color=&#8217;#333333&#8242; svg_div_bottom_width=&#8217;100&#8242; svg_div_bottom_height=&#8217;50&#8217; svg_div_bottom_max_height=&#8217;none&#8217; svg_div_bottom_opacity=&#8221; column_boxshadow_width=&#8217;10&#8217; column_boxshadow_color=&#8221; background=&#8217;bg_color&#8217; background_color=&#8221; background_gradient_direction=&#8217;vertical&#8217; background_gradient_color1=&#8217;#000000&#8242; background_gradient_color2=&#8217;#ffffff&#8217; background_gradient_color3=&#8221; src=&#8221; attachment=&#8221; attachment_size=&#8221; background_position=&#8217;top left&#8217; background_repeat=&#8217;no-repeat&#8217; highlight_size=&#8217;1.1&#8242; animation=&#8221; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; parallax_parallax=&#8221; parallax_parallax_speed=&#8221; av-desktop-parallax_parallax=&#8221; av-desktop-parallax_parallax_speed=&#8221; av-medium-parallax_parallax=&#8221; av-medium-parallax_parallax_speed=&#8221; av-small-parallax_parallax=&#8221; av-small-parallax_parallax_speed=&#8221; av-mini-parallax_parallax=&#8221; av-mini-parallax_parallax_speed=&#8221; css_position=&#8221; css_position_location=&#8217;,,,&#8217; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8217;,,,&#8217; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8217;,,,&#8217; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8217;,,,&#8217; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8217;,,,&#8217; av-mini-css_position_z_index=&#8221; link=&#8221; linktarget=&#8221; link_hover=&#8221; title_attr=&#8221; alt_attr=&#8221; mobile_display=&#8221; mobile_col_pos=&#8217;0&#8242; id=&#8221; custom_class=&#8221; template_class=&#8221; aria_label=&#8221; av_uid=&#8217;av-b0gmae&#8217; sc_version=&#8217;1.0&#8242;]<br \/>\n[av_image src=&#8217;http:\/\/manpro.id\/product\/wp-content\/uploads\/2023\/05\/Window-app-new-02-300&#215;150.png&#8217; attachment=&#8217;5164&#8242; attachment_size=&#8217;medium&#8217; copyright=&#8221; caption=&#8221; image_size=&#8217;no scaling&#8217; styling=&#8221; box_shadow=&#8217;none&#8217; box_shadow_width=&#8217;10&#8217; box_shadow_color=&#8221; align=&#8217;center&#8217; font_size=&#8221; overlay_opacity=&#8217;0.4&#8242; overlay_color=&#8217;#000000&#8242; overlay_text_color=&#8217;#ffffff&#8217; link=&#8221; target=&#8221; animation=&#8217;no-animation&#8217; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; parallax_parallax=&#8221; parallax_parallax_speed=&#8221; av-desktop-parallax_parallax=&#8221; av-desktop-parallax_parallax_speed=&#8221; av-medium-parallax_parallax=&#8221; av-medium-parallax_parallax_speed=&#8221; av-small-parallax_parallax=&#8221; av-small-parallax_parallax_speed=&#8221; av-mini-parallax_parallax=&#8221; av-mini-parallax_parallax_speed=&#8221; hover=&#8221; blur_image=&#8221; grayscale_image=&#8221; fade_image=&#8221; appearance=&#8221; css_position=&#8221; css_position_location=&#8217;,,,&#8217; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8217;,,,&#8217; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8217;,,,&#8217; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8217;,,,&#8217; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8217;,,,&#8217; av-mini-css_position_z_index=&#8221; transform_perspective=&#8221; transform_rotation=&#8217;,,,&#8217; transform_scale=&#8217;,,&#8217; transform_skew=&#8217;,&#8217; transform_translate=&#8217;,,&#8217; av-desktop-transform_perspective=&#8221; av-desktop-transform_rotation=&#8217;,,,&#8217; av-desktop-transform_scale=&#8217;,,&#8217; av-desktop-transform_skew=&#8217;,&#8217; av-desktop-transform_translate=&#8217;,,&#8217; av-medium-transform_perspective=&#8221; av-medium-transform_rotation=&#8217;,,,&#8217; av-medium-transform_scale=&#8217;,,&#8217; av-medium-transform_skew=&#8217;,&#8217; av-medium-transform_translate=&#8217;,,&#8217; av-small-transform_perspective=&#8221; av-small-transform_rotation=&#8217;,,,&#8217; av-small-transform_scale=&#8217;,,&#8217; av-small-transform_skew=&#8217;,&#8217; av-small-transform_translate=&#8217;,,&#8217; av-mini-transform_perspective=&#8221; av-mini-transform_rotation=&#8217;,,,&#8217; av-mini-transform_scale=&#8217;,,&#8217; av-mini-transform_skew=&#8217;,&#8217; av-mini-transform_translate=&#8217;,,&#8217; mask_overlay=&#8221; mask_overlay_shape=&#8217;blob&#8217; mask_overlay_size=&#8217;contain&#8217; mask_overlay_scale=&#8217;100%&#8217; mask_overlay_position=&#8217;center center&#8217; mask_overlay_repeat=&#8217;no-repeat&#8217; mask_overlay_rotate=&#8221; mask_overlay_rad_shape=&#8217;circle&#8217; mask_overlay_rad_position=&#8217;center center&#8217; mask_overlay_opacity1=&#8217;0&#8242; mask_overlay_opacity2=&#8217;1&#8242; mask_overlay_opacity3=&#8221; title_attr=&#8221; alt_attr=&#8221; img_scrset=&#8221; lazy_loading=&#8217;disabled&#8217; id=&#8221; custom_class=&#8221; template_class=&#8221; av_element_hidden_in_editor=&#8217;0&#8242; av_uid=&#8217;av-lgynsv6v&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;][\/av_image]<br \/>\n[\/av_one_half]<\/p>\n<p>[av_one_half min_height=&#8221; vertical_alignment=&#8217;av-align-top&#8217; space=&#8221; row_boxshadow=&#8221; row_boxshadow_width=&#8217;10&#8217; row_boxshadow_color=&#8221; custom_margin=&#8221; margin=&#8217;0px&#8217; av-desktop-margin=&#8221; av-medium-margin=&#8221; av-small-margin=&#8221; av-mini-margin=&#8221; mobile_breaking=&#8221; mobile_column_order=&#8221; border=&#8221; border_style=&#8217;solid&#8217; border_color=&#8221; radius=&#8221; min_col_height=&#8221; padding=&#8221; av-desktop-padding=&#8221; av-medium-padding=&#8221; av-small-padding=&#8221; av-mini-padding=&#8221; svg_div_top=&#8221; svg_div_top_color=&#8217;#333333&#8242; svg_div_top_width=&#8217;100&#8242; svg_div_top_height=&#8217;50&#8217; svg_div_top_max_height=&#8217;none&#8217; svg_div_top_flip=&#8221; svg_div_top_invert=&#8221; svg_div_top_front=&#8221; svg_div_top_opacity=&#8221; svg_div_top_preview=&#8221; svg_div_bottom=&#8221; svg_div_bottom_color=&#8217;#333333&#8242; svg_div_bottom_width=&#8217;100&#8242; svg_div_bottom_height=&#8217;50&#8217; svg_div_bottom_max_height=&#8217;none&#8217; svg_div_bottom_flip=&#8221; svg_div_bottom_invert=&#8221; svg_div_bottom_front=&#8221; svg_div_bottom_opacity=&#8221; svg_div_bottom_preview=&#8221; column_boxshadow=&#8221; column_boxshadow_width=&#8217;10&#8217; column_boxshadow_color=&#8221; background=&#8217;bg_color&#8217; background_color=&#8221; background_gradient_direction=&#8217;vertical&#8217; background_gradient_color1=&#8217;#000000&#8242; background_gradient_color2=&#8217;#ffffff&#8217; background_gradient_color3=&#8221; src=&#8221; background_position=&#8217;top left&#8217; background_repeat=&#8217;no-repeat&#8217; highlight=&#8221; highlight_size=&#8221; animation=&#8221; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; parallax_parallax=&#8221; parallax_parallax_speed=&#8221; av-desktop-parallax_parallax=&#8221; av-desktop-parallax_parallax_speed=&#8221; av-medium-parallax_parallax=&#8221; av-medium-parallax_parallax_speed=&#8221; av-small-parallax_parallax=&#8221; av-small-parallax_parallax_speed=&#8221; av-mini-parallax_parallax=&#8221; av-mini-parallax_parallax_speed=&#8221; css_position=&#8221; css_position_location=&#8221; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8221; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8221; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8221; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8221; av-mini-css_position_z_index=&#8221; link=&#8221; linktarget=&#8221; link_hover=&#8221; title_attr=&#8221; alt_attr=&#8221; mobile_display=&#8221; mobile_col_pos=&#8217;0&#8242; id=&#8221; custom_class=&#8221; template_class=&#8221; aria_label=&#8221; av_uid=&#8217;av-br8p2u&#8217; sc_version=&#8217;1.0&#8242;]<br \/>\n[av_textblock textblock_styling_align=&#8221; textblock_styling=&#8221; textblock_styling_gap=&#8221; textblock_styling_mobile=&#8221; size=&#8217;18&#8217; av-desktop-font-size=&#8217;18&#8217; av-medium-font-size=&#8217;18&#8217; av-small-font-size=&#8217;18&#8217; av-mini-font-size=&#8217;18&#8217; font_color=&#8217;custom&#8217; color=&#8217;#e8500e&#8217; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-lib4ms9n&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<h3 class=\"judul mobile-hidden ml20\" style=\"max-width: 85%; font-size: 30px; font-weight: 500;\">Galeri Foto<\/h3>\n<p>[\/av_textblock]<\/p>\n<p>[av_textblock textblock_styling_align=&#8221; textblock_styling=&#8221; textblock_styling_gap=&#8221; textblock_styling_mobile=&#8221; size=&#8221; av-desktop-font-size=&#8221; av-medium-font-size=&#8221; av-small-font-size=&#8221; av-mini-font-size=&#8221; font_color=&#8217;custom&#8217; color=&#8217;#717173&#8242; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-lgynuiag&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<h4 class=\"mobile-hidden\" style=\"line-height: 1.8; letter-spacing: 0.5px;\">Upload foto \/ video yang dapat disertakan komentar dan disusun per album<\/h4>\n<p>[\/av_textblock]<\/p>\n<p>[av_iconlist position=&#8217;left&#8217; iconlist_styling=&#8217;av-iconlist-small&#8217; custom_title_size=&#8221; av-desktop-font-size-title=&#8221; av-medium-font-size-title=&#8221; av-small-font-size-title=&#8221; av-mini-font-size-title=&#8221; custom_content_size=&#8221; av-desktop-font-size=&#8221; av-medium-font-size=&#8221; av-small-font-size=&#8221; av-mini-font-size=&#8221; font_color=&#8217;custom&#8217; custom_title=&#8217;#717173&#8242; custom_content=&#8217;#717173&#8242; color=&#8217;custom&#8217; custom_font=&#8217;#ffffff&#8217; custom_bg=&#8217;#e8500e&#8217; custom_border=&#8221; gradient_color_direction=&#8217;vertical&#8217; gradient_color_1=&#8217;#000000&#8242; gradient_color_2=&#8217;#ffffff&#8217; gradient_color_3=&#8221; border=&#8221; border_width=&#8221; border_width_sync=&#8217;true&#8217; border_color=&#8221; box_shadow=&#8221; box_shadow_style=&#8217;0px,0px,0px,0px&#8217; box_shadow_color=&#8221; animation=&#8221; sonar_effect_effect=&#8221; sonar_effect_color=&#8221; sonar_effect_duration=&#8217;1&#8242; sonar_effect_scale=&#8221; sonar_effect_opac=&#8217;0.5&#8242; alb_description=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-6t8imu&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<br \/>\n[av_iconlist_item title=&#8221; icon=&#8217;ue812&#8242; font=&#8217;entypo-fontello&#8217; heading_tag=&#8221; heading_class=&#8221; link=&#8221; linktarget=&#8221; linkelement=&#8221; av_uid=&#8217;av-65o6ie&#8217; sc_version=&#8217;1.0&#8242;]<\/p>\n<h4 class=\"mobile-hidden\" style=\"line-height: 1.8; letter-spacing: 0.5px; padding-left: 10px;\">Upload foto video dan buat update per album<\/h4>\n<p>[\/av_iconlist_item]<br \/>\n[av_iconlist_item title=&#8221; icon=&#8217;ue812&#8242; font=&#8217;entypo-fontello&#8217; heading_tag=&#8221; heading_class=&#8221; link=&#8221; linktarget=&#8221; linkelement=&#8221; av_uid=&#8217;av-ditpi&#8217; sc_version=&#8217;1.0&#8242;]<\/p>\n<h4 class=\"mobile-hidden\" style=\"line-height: 1.8; letter-spacing: 0.5px; padding-left: 10px;\">Dilengkapi dengan fitur meta data untuk akurasi informasi foto<\/h4>\n<p>[\/av_iconlist_item]<br \/>\n[\/av_iconlist]<br \/>\n[\/av_one_half]<\/p>\n<p>[av_section min_height=&#8221; min_height_pc=&#8217;25&#8217; min_height_px=&#8217;500px&#8217; shadow=&#8217;no-border-styling&#8217; bottom_border=&#8217;no-border-styling&#8217; bottom_border_diagonal_color=&#8217;#333333&#8242; bottom_border_diagonal_direction=&#8221; bottom_border_style=&#8221; padding=&#8217;default&#8217; custom_margin=&#8217;0px&#8217; custom_margin_sync=&#8217;true&#8217; av-desktop-custom_margin=&#8221; av-desktop-custom_margin_sync=&#8217;true&#8217; av-medium-custom_margin=&#8221; av-medium-custom_margin_sync=&#8217;true&#8217; av-small-custom_margin=&#8221; av-small-custom_margin_sync=&#8217;true&#8217; av-mini-custom_margin=&#8221; av-mini-custom_margin_sync=&#8217;true&#8217; svg_div_top=&#8221; svg_div_top_color=&#8217;#333333&#8242; svg_div_top_width=&#8217;100&#8242; svg_div_top_height=&#8217;50&#8217; svg_div_top_max_height=&#8217;none&#8217; svg_div_top_opacity=&#8221; svg_div_bottom=&#8221; svg_div_bottom_color=&#8217;#333333&#8242; svg_div_bottom_width=&#8217;100&#8242; svg_div_bottom_height=&#8217;50&#8217; svg_div_bottom_max_height=&#8217;none&#8217; svg_div_bottom_opacity=&#8221; color=&#8217;main_color&#8217; background=&#8217;bg_color&#8217; custom_bg=&#8217;#eaeaea&#8217; background_gradient_direction=&#8217;vertical&#8217; background_gradient_color1=&#8217;#000000&#8242; background_gradient_color2=&#8217;#ffffff&#8217; background_gradient_color3=&#8221; src=&#8221; attachment=&#8221; attachment_size=&#8221; attach=&#8217;scroll&#8217; position=&#8217;top left&#8217; repeat=&#8217;no-repeat&#8217; video=&#8221; video_ratio=&#8217;16:9&#8242; overlay_opacity=&#8217;0.5&#8242; overlay_color=&#8221; overlay_pattern=&#8221; overlay_custom_pattern=&#8221; custom_arrow_bg=&#8221; css_position_z_index=&#8221; av-desktop-css_position_z_index=&#8221; av-medium-css_position_z_index=&#8221; av-small-css_position_z_index=&#8221; av-mini-css_position_z_index=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; aria_label=&#8221; av_element_hidden_in_editor=&#8217;0&#8242; av_uid=&#8217;av-lhyo0c9k&#8217; sc_version=&#8217;1.0&#8242;]<\/p>\n<p>[av_hr class=&#8217;invisible&#8217; icon_select=&#8217;yes&#8217; icon=&#8217;ue808&#8242; font=&#8217;entypo-fontello&#8217; position=&#8217;center&#8217; shadow=&#8217;no-shadow&#8217; height=&#8217;25&#8217; custom_border=&#8217;av-border-thin&#8217; custom_width=&#8217;50px&#8217; custom_margin_top=&#8217;30px&#8217; custom_margin_bottom=&#8217;30px&#8217; custom_border_color=&#8221; custom_icon_color=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-lhyna63s&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<p>[av_one_third first min_height=&#8221; vertical_alignment=&#8217;av-align-top&#8217; space=&#8221; row_boxshadow_width=&#8217;10&#8217; row_boxshadow_color=&#8221; margin=&#8217;0px&#8217; margin_sync=&#8217;true&#8217; av-desktop-margin=&#8221; av-desktop-margin_sync=&#8217;true&#8217; av-medium-margin=&#8221; av-medium-margin_sync=&#8217;true&#8217; av-small-margin=&#8221; av-small-margin_sync=&#8217;true&#8217; av-mini-margin=&#8221; av-mini-margin_sync=&#8217;true&#8217; mobile_breaking=&#8221; mobile_column_order=&#8221; border=&#8221; border_style=&#8217;solid&#8217; border_color=&#8221; radius=&#8221; radius_sync=&#8217;true&#8217; min_col_height=&#8221; padding=&#8221; padding_sync=&#8217;true&#8217; av-desktop-padding=&#8221; av-desktop-padding_sync=&#8217;true&#8217; av-medium-padding=&#8221; av-medium-padding_sync=&#8217;true&#8217; av-small-padding=&#8221; av-small-padding_sync=&#8217;true&#8217; av-mini-padding=&#8221; av-mini-padding_sync=&#8217;true&#8217; svg_div_top=&#8221; svg_div_top_color=&#8217;#333333&#8242; svg_div_top_width=&#8217;100&#8242; svg_div_top_height=&#8217;50&#8217; svg_div_top_max_height=&#8217;none&#8217; svg_div_top_opacity=&#8221; svg_div_bottom=&#8221; svg_div_bottom_color=&#8217;#333333&#8242; svg_div_bottom_width=&#8217;100&#8242; svg_div_bottom_height=&#8217;50&#8217; svg_div_bottom_max_height=&#8217;none&#8217; svg_div_bottom_opacity=&#8221; column_boxshadow_width=&#8217;10&#8217; column_boxshadow_color=&#8221; background=&#8217;bg_color&#8217; background_color=&#8221; background_gradient_direction=&#8217;vertical&#8217; background_gradient_color1=&#8217;#000000&#8242; background_gradient_color2=&#8217;#ffffff&#8217; background_gradient_color3=&#8221; src=&#8221; attachment=&#8221; attachment_size=&#8221; background_position=&#8217;top left&#8217; background_repeat=&#8217;no-repeat&#8217; highlight_size=&#8217;1.1&#8242; animation=&#8221; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; parallax_parallax=&#8221; parallax_parallax_speed=&#8221; av-desktop-parallax_parallax=&#8221; av-desktop-parallax_parallax_speed=&#8221; av-medium-parallax_parallax=&#8221; av-medium-parallax_parallax_speed=&#8221; av-small-parallax_parallax=&#8221; av-small-parallax_parallax_speed=&#8221; av-mini-parallax_parallax=&#8221; av-mini-parallax_parallax_speed=&#8221; css_position=&#8221; css_position_location=&#8217;,,,&#8217; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8217;,,,&#8217; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8217;,,,&#8217; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8217;,,,&#8217; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8217;,,,&#8217; av-mini-css_position_z_index=&#8221; link=&#8221; linktarget=&#8221; link_hover=&#8221; title_attr=&#8221; alt_attr=&#8221; mobile_display=&#8221; mobile_col_pos=&#8217;0&#8242; id=&#8221; custom_class=&#8221; template_class=&#8221; aria_label=&#8221; av_uid=&#8217;av-80uip2&#8242; sc_version=&#8217;1.0&#8242;]<\/p>\n<p>[av_font_icon icon=&#8217;ue8a5&#8242; font=&#8217;entypo-fontello&#8217; style=&#8221; caption=&#8221; size=&#8217;60px&#8217; position=&#8217;center&#8217; color=&#8217;#e8500e&#8217; link=&#8221; linktarget=&#8221; sonar_effect_effect=&#8221; sonar_effect_color=&#8221; sonar_effect_duration=&#8217;1&#8242; sonar_effect_scale=&#8221; sonar_effect_opac=&#8217;0.5&#8242; animation=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-lhynwnjl&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;][\/av_font_icon]<\/p>\n<p>[av_hr class=&#8217;invisible&#8217; icon_select=&#8217;yes&#8217; icon=&#8217;ue808&#8242; font=&#8217;entypo-fontello&#8217; position=&#8217;center&#8217; shadow=&#8217;no-shadow&#8217; height=&#8217;30&#8217; custom_border=&#8217;av-border-thin&#8217; custom_width=&#8217;50px&#8217; custom_margin_top=&#8217;30px&#8217; custom_margin_bottom=&#8217;30px&#8217; custom_border_color=&#8221; custom_icon_color=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-lhyrixei&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<p>[av_textblock textblock_styling_align=&#8221; textblock_styling=&#8221; textblock_styling_gap=&#8221; textblock_styling_mobile=&#8221; size=&#8217;18&#8217; av-desktop-font-size=&#8217;18&#8217; av-medium-font-size=&#8217;18&#8217; av-small-font-size=&#8217;18&#8217; av-mini-font-size=&#8217;18&#8217; font_color=&#8217;custom&#8217; color=&#8217;#e8500e&#8217; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-li9z3x7f&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<h3 class=\"judul mobile-hidden ml20\" style=\"text-align: center;\">Standardisasi Proyek<\/h3>\n<p>[\/av_textblock]<\/p>\n<p>[av_textblock textblock_styling_align=&#8221; textblock_styling=&#8221; textblock_styling_gap=&#8221; textblock_styling_mobile=&#8221; size=&#8221; av-desktop-font-size=&#8221; av-medium-font-size=&#8221; av-small-font-size=&#8221; av-mini-font-size=&#8221; font_color=&#8217;custom&#8217; color=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-63eqeu&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<p class=\"mobile-hidden ml20\" style=\"text-align: center;\">\u00a0Standardkan seluruh proyek Anda dalam satu rangkaian dokumentasi dan alur kerja<\/p>\n<div class=\"mobile-hidden\"><\/div>\n<p>[\/av_textblock]<\/p>\n<p>[\/av_one_third][av_one_third min_height=&#8221; vertical_alignment=&#8217;av-align-top&#8217; space=&#8221; row_boxshadow_width=&#8217;10&#8217; row_boxshadow_color=&#8221; margin=&#8217;0px&#8217; margin_sync=&#8217;true&#8217; av-desktop-margin=&#8221; av-desktop-margin_sync=&#8217;true&#8217; av-medium-margin=&#8221; av-medium-margin_sync=&#8217;true&#8217; av-small-margin=&#8221; av-small-margin_sync=&#8217;true&#8217; av-mini-margin=&#8221; av-mini-margin_sync=&#8217;true&#8217; mobile_breaking=&#8221; mobile_column_order=&#8221; border=&#8221; border_style=&#8217;solid&#8217; border_color=&#8221; radius=&#8221; radius_sync=&#8217;true&#8217; min_col_height=&#8221; padding=&#8221; padding_sync=&#8217;true&#8217; av-desktop-padding=&#8221; av-desktop-padding_sync=&#8217;true&#8217; av-medium-padding=&#8221; av-medium-padding_sync=&#8217;true&#8217; av-small-padding=&#8221; av-small-padding_sync=&#8217;true&#8217; av-mini-padding=&#8221; av-mini-padding_sync=&#8217;true&#8217; svg_div_top=&#8221; svg_div_top_color=&#8217;#333333&#8242; svg_div_top_width=&#8217;100&#8242; svg_div_top_height=&#8217;50&#8217; svg_div_top_max_height=&#8217;none&#8217; svg_div_top_opacity=&#8221; svg_div_bottom=&#8221; svg_div_bottom_color=&#8217;#333333&#8242; svg_div_bottom_width=&#8217;100&#8242; svg_div_bottom_height=&#8217;50&#8217; svg_div_bottom_max_height=&#8217;none&#8217; svg_div_bottom_opacity=&#8221; column_boxshadow_width=&#8217;10&#8217; column_boxshadow_color=&#8221; background=&#8217;bg_color&#8217; background_color=&#8221; background_gradient_direction=&#8217;vertical&#8217; background_gradient_color1=&#8217;#000000&#8242; background_gradient_color2=&#8217;#ffffff&#8217; background_gradient_color3=&#8221; src=&#8221; attachment=&#8221; attachment_size=&#8221; background_position=&#8217;top left&#8217; background_repeat=&#8217;no-repeat&#8217; highlight_size=&#8217;1.1&#8242; animation=&#8221; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; parallax_parallax=&#8221; parallax_parallax_speed=&#8221; av-desktop-parallax_parallax=&#8221; av-desktop-parallax_parallax_speed=&#8221; av-medium-parallax_parallax=&#8221; av-medium-parallax_parallax_speed=&#8221; av-small-parallax_parallax=&#8221; av-small-parallax_parallax_speed=&#8221; av-mini-parallax_parallax=&#8221; av-mini-parallax_parallax_speed=&#8221; css_position=&#8221; css_position_location=&#8217;,,,&#8217; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8217;,,,&#8217; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8217;,,,&#8217; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8217;,,,&#8217; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8217;,,,&#8217; av-mini-css_position_z_index=&#8221; link=&#8221; linktarget=&#8221; link_hover=&#8221; title_attr=&#8221; alt_attr=&#8221; mobile_display=&#8221; mobile_col_pos=&#8217;0&#8242; id=&#8221; custom_class=&#8221; template_class=&#8221; aria_label=&#8221; av_uid=&#8217;av-113sza&#8217; sc_version=&#8217;1.0&#8242;]<\/p>\n<p>[av_font_icon icon=&#8217;ue8ac&#8217; font=&#8217;entypo-fontello&#8217; style=&#8221; caption=&#8221; size=&#8217;60px&#8217; position=&#8217;center&#8217; color=&#8217;#e8500e&#8217; link=&#8221; linktarget=&#8221; sonar_effect_effect=&#8221; sonar_effect_color=&#8221; sonar_effect_duration=&#8217;1&#8242; sonar_effect_scale=&#8221; sonar_effect_opac=&#8217;0.5&#8242; animation=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-3ljs2u&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;][\/av_font_icon]<\/p>\n<p>[av_hr class=&#8217;invisible&#8217; icon_select=&#8217;yes&#8217; icon=&#8217;ue808&#8242; font=&#8217;entypo-fontello&#8217; position=&#8217;center&#8217; shadow=&#8217;no-shadow&#8217; height=&#8217;30&#8217; custom_border=&#8217;av-border-thin&#8217; custom_width=&#8217;50px&#8217; custom_margin_top=&#8217;30px&#8217; custom_margin_bottom=&#8217;30px&#8217; custom_border_color=&#8221; custom_icon_color=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-48elzq&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<p>[av_textblock textblock_styling_align=&#8221; textblock_styling=&#8221; textblock_styling_gap=&#8221; textblock_styling_mobile=&#8221; size=&#8217;18&#8217; av-desktop-font-size=&#8217;18&#8217; av-medium-font-size=&#8217;18&#8217; av-small-font-size=&#8217;18&#8217; av-mini-font-size=&#8217;18&#8217; font_color=&#8217;custom&#8217; color=&#8217;#e8500e&#8217; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-li9zez9d&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<h3 class=\"judul mobile-hidden ml20\" style=\"text-align: center;\">Paperless<\/h3>\n<p>[\/av_textblock]<\/p>\n<p>[av_textblock textblock_styling_align=&#8221; textblock_styling=&#8221; textblock_styling_gap=&#8221; textblock_styling_mobile=&#8221; size=&#8221; av-desktop-font-size=&#8221; av-medium-font-size=&#8221; av-small-font-size=&#8221; av-mini-font-size=&#8221; font_color=&#8217;custom&#8217; color=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-7yri2u&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<p class=\"mobile-hidden ml20\" style=\"text-align: center;\">Beralih dari sistem manual ke digital yang paperless dan efisien<\/p>\n<div class=\"mobile-hidden\"><\/div>\n<p>[\/av_textblock]<\/p>\n<p>[\/av_one_third][av_one_third min_height=&#8221; vertical_alignment=&#8217;av-align-top&#8217; space=&#8221; row_boxshadow_width=&#8217;10&#8217; row_boxshadow_color=&#8221; margin=&#8217;0px&#8217; margin_sync=&#8217;true&#8217; av-desktop-margin=&#8221; av-desktop-margin_sync=&#8217;true&#8217; av-medium-margin=&#8221; av-medium-margin_sync=&#8217;true&#8217; av-small-margin=&#8221; av-small-margin_sync=&#8217;true&#8217; av-mini-margin=&#8221; av-mini-margin_sync=&#8217;true&#8217; mobile_breaking=&#8221; mobile_column_order=&#8221; border=&#8221; border_style=&#8217;solid&#8217; border_color=&#8221; radius=&#8221; radius_sync=&#8217;true&#8217; min_col_height=&#8221; padding=&#8221; padding_sync=&#8217;true&#8217; av-desktop-padding=&#8221; av-desktop-padding_sync=&#8217;true&#8217; av-medium-padding=&#8221; av-medium-padding_sync=&#8217;true&#8217; av-small-padding=&#8221; av-small-padding_sync=&#8217;true&#8217; av-mini-padding=&#8221; av-mini-padding_sync=&#8217;true&#8217; svg_div_top=&#8221; svg_div_top_color=&#8217;#333333&#8242; svg_div_top_width=&#8217;100&#8242; svg_div_top_height=&#8217;50&#8217; svg_div_top_max_height=&#8217;none&#8217; svg_div_top_opacity=&#8221; svg_div_bottom=&#8221; svg_div_bottom_color=&#8217;#333333&#8242; svg_div_bottom_width=&#8217;100&#8242; svg_div_bottom_height=&#8217;50&#8217; svg_div_bottom_max_height=&#8217;none&#8217; svg_div_bottom_opacity=&#8221; column_boxshadow_width=&#8217;10&#8217; column_boxshadow_color=&#8221; background=&#8217;bg_color&#8217; background_color=&#8221; background_gradient_direction=&#8217;vertical&#8217; background_gradient_color1=&#8217;#000000&#8242; background_gradient_color2=&#8217;#ffffff&#8217; background_gradient_color3=&#8221; src=&#8221; attachment=&#8221; attachment_size=&#8221; background_position=&#8217;top left&#8217; background_repeat=&#8217;no-repeat&#8217; highlight_size=&#8217;1.1&#8242; animation=&#8221; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; parallax_parallax=&#8221; parallax_parallax_speed=&#8221; av-desktop-parallax_parallax=&#8221; av-desktop-parallax_parallax_speed=&#8221; av-medium-parallax_parallax=&#8221; av-medium-parallax_parallax_speed=&#8221; av-small-parallax_parallax=&#8221; av-small-parallax_parallax_speed=&#8221; av-mini-parallax_parallax=&#8221; av-mini-parallax_parallax_speed=&#8221; css_position=&#8221; css_position_location=&#8217;,,,&#8217; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8217;,,,&#8217; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8217;,,,&#8217; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8217;,,,&#8217; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8217;,,,&#8217; av-mini-css_position_z_index=&#8221; link=&#8221; linktarget=&#8221; link_hover=&#8221; title_attr=&#8221; alt_attr=&#8221; mobile_display=&#8221; mobile_col_pos=&#8217;0&#8242; id=&#8221; custom_class=&#8221; template_class=&#8221; aria_label=&#8221; av_uid=&#8217;av-9swz3q&#8217; sc_version=&#8217;1.0&#8242;]<\/p>\n<p>[av_font_icon icon=&#8217;ue810&#8242; font=&#8217;entypo-fontello&#8217; style=&#8221; caption=&#8221; size=&#8217;60px&#8217; position=&#8217;center&#8217; color=&#8217;#e8500e&#8217; link=&#8221; linktarget=&#8221; sonar_effect_effect=&#8221; sonar_effect_color=&#8221; sonar_effect_duration=&#8217;1&#8242; sonar_effect_scale=&#8221; sonar_effect_opac=&#8217;0.5&#8242; animation=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-xxp2&#8242; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;][\/av_font_icon]<\/p>\n<p>[av_hr class=&#8217;invisible&#8217; icon_select=&#8217;yes&#8217; icon=&#8217;ue808&#8242; font=&#8217;entypo-fontello&#8217; position=&#8217;center&#8217; shadow=&#8217;no-shadow&#8217; height=&#8217;30&#8217; custom_border=&#8217;av-border-thin&#8217; custom_width=&#8217;50px&#8217; custom_margin_top=&#8217;30px&#8217; custom_margin_bottom=&#8217;30px&#8217; custom_border_color=&#8221; custom_icon_color=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-5xnopi&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<p>[av_textblock textblock_styling_align=&#8221; textblock_styling=&#8221; textblock_styling_gap=&#8221; textblock_styling_mobile=&#8221; size=&#8217;18&#8217; av-desktop-font-size=&#8217;18&#8217; av-medium-font-size=&#8217;18&#8217; av-small-font-size=&#8217;18&#8217; av-mini-font-size=&#8217;18&#8217; font_color=&#8217;custom&#8217; color=&#8217;#e8500e&#8217; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-486ohy&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<h3 class=\"judul mobile-hidden ml20\" style=\"text-align: center;\">1 Sumber Informasi<\/h3>\n<p>[\/av_textblock]<\/p>\n<p>[av_textblock textblock_styling_align=&#8221; textblock_styling=&#8221; textblock_styling_gap=&#8221; textblock_styling_mobile=&#8221; size=&#8221; av-desktop-font-size=&#8221; av-medium-font-size=&#8221; av-small-font-size=&#8221; av-mini-font-size=&#8221; font_color=&#8217;custom&#8217; color=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-21r19i&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<p class=\"mobile-hidden ml20\" style=\"text-align: center;\">Kemudahan pencarian informasi dan data proyek yang akurat<\/p>\n<div class=\"mobile-hidden\"><\/div>\n<p>[\/av_textblock]<\/p>\n<p>[\/av_one_third][av_hr class=&#8217;invisible&#8217; icon_select=&#8217;yes&#8217; icon=&#8217;ue808&#8242; font=&#8217;entypo-fontello&#8217; position=&#8217;center&#8217; shadow=&#8217;no-shadow&#8217; height=&#8217;25&#8217; custom_border=&#8217;av-border-thin&#8217; custom_width=&#8217;50px&#8217; custom_margin_top=&#8217;30px&#8217; custom_margin_bottom=&#8217;30px&#8217; custom_border_color=&#8221; custom_icon_color=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-lhynyxph&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<p>[av_button label=&#8217;Jadwalkan Demo&#8217; icon_select=&#8217;yes&#8217; icon=&#8217;ue8b7&#8242; font=&#8217;entypo-fontello&#8217; link=&#8217;manually,http:\/\/&#8217; link_target=&#8221; size=&#8217;large&#8217; position=&#8217;center&#8217; label_display=&#8221; title_attr=&#8221; size-text=&#8217;22&#8217; av-desktop-font-size-text=&#8221; av-medium-font-size-text=&#8221; av-small-font-size-text=&#8221; av-mini-font-size-text=&#8221; margin=&#8221; margin_sync=&#8217;true&#8217; padding=&#8221; padding_sync=&#8217;true&#8217; av-desktop-margin=&#8221; av-desktop-margin_sync=&#8217;true&#8217; av-desktop-padding=&#8221; av-desktop-padding_sync=&#8217;true&#8217; av-medium-margin=&#8221; av-medium-margin_sync=&#8217;true&#8217; av-medium-padding=&#8221; av-medium-padding_sync=&#8217;true&#8217; av-small-margin=&#8221; av-small-margin_sync=&#8217;true&#8217; av-small-padding=&#8221; av-small-padding_sync=&#8217;true&#8217; av-mini-margin=&#8221; av-mini-margin_sync=&#8217;true&#8217; av-mini-padding=&#8221; av-mini-padding_sync=&#8217;true&#8217; color_options=&#8221; color=&#8217;custom&#8217; custom_bg=&#8217;#e8500e&#8217; custom_font=&#8217;#ffffff&#8217; btn_color_bg=&#8217;theme-color&#8217; btn_custom_grad_direction=&#8217;vertical&#8217; btn_custom_grad_1=&#8217;#000000&#8242; btn_custom_grad_2=&#8217;#ffffff&#8217; btn_custom_grad_3=&#8221; btn_custom_grad_opacity=&#8217;0.7&#8242; btn_custom_bg=&#8217;#444444&#8242; btn_color_bg_hover=&#8217;theme-color-highlight&#8217; btn_custom_bg_hover=&#8217;#444444&#8242; btn_color_font=&#8217;theme-color&#8217; btn_custom_font=&#8217;#ffffff&#8217; btn_color_font_hover=&#8217;white&#8217; btn_custom_font_hover=&#8217;#ffffff&#8217; border=&#8221; border_width=&#8221; border_width_sync=&#8217;true&#8217; border_color=&#8221; border_radius=&#8221; border_radius_sync=&#8217;true&#8217; box_shadow=&#8221; box_shadow_style=&#8217;0px,0px,0px,0px&#8217; box_shadow_color=&#8221; animation=&#8221; animation_duration=&#8221; animation_custom_bg_color=&#8221; animation_z_index_curtain=&#8217;100&#8242; hover_opacity=&#8221; sonar_effect_effect=&#8221; sonar_effect_color=&#8221; sonar_effect_duration=&#8217;1&#8242; sonar_effect_scale=&#8221; sonar_effect_opac=&#8217;0.5&#8242; css_position=&#8221; css_position_location=&#8217;,,,&#8217; css_position_z_index=&#8221; av-desktop-css_position=&#8221; av-desktop-css_position_location=&#8217;,,,&#8217; av-desktop-css_position_z_index=&#8221; av-medium-css_position=&#8221; av-medium-css_position_location=&#8217;,,,&#8217; av-medium-css_position_z_index=&#8221; av-small-css_position=&#8221; av-small-css_position_location=&#8217;,,,&#8217; av-small-css_position_z_index=&#8221; av-mini-css_position=&#8221; av-mini-css_position_location=&#8217;,,,&#8217; av-mini-css_position_z_index=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-2zxbdy&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<p>[av_hr class=&#8217;invisible&#8217; icon_select=&#8217;yes&#8217; icon=&#8217;ue808&#8242; font=&#8217;entypo-fontello&#8217; position=&#8217;center&#8217; shadow=&#8217;no-shadow&#8217; height=&#8217;15&#8217; custom_border=&#8217;av-border-thin&#8217; custom_width=&#8217;50px&#8217; custom_margin_top=&#8217;30px&#8217; custom_margin_bottom=&#8217;30px&#8217; custom_border_color=&#8221; custom_icon_color=&#8221; id=&#8221; custom_class=&#8221; template_class=&#8221; av_uid=&#8217;av-1vuexy&#8217; sc_version=&#8217;1.0&#8242; admin_preview_bg=&#8221;]<\/p>\n<p>[\/av_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[av_section min_height=&#8217;custom&#8217; min_height_pc=&#8217;25&#8217; min_height_px=&#8217;500&#8242; shadow=&#8217;no-border-styling&#8217; bottom_border=&#8217;no-border-styling&#8217; bottom_border_diagonal_color=&#8217;#333333&#8242; bottom_border_diagonal_direction=&#8221; bottom_border_style=&#8221; padding=&#8217;default&#8217; custom_margin=&#8217;0px&#8217; custom_margin_sync=&#8217;true&#8217; av-desktop-custom_margin=&#8221; av-desktop-custom_margin_sync=&#8217;true&#8217; av-medium-custom_margin=&#8221; av-medium-custom_margin_sync=&#8217;true&#8217; av-small-custom_margin=&#8221; av-small-custom_margin_sync=&#8217;true&#8217; av-mini-custom_margin=&#8221; av-mini-custom_margin_sync=&#8217;true&#8217; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-3318","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Reporting -<\/title>\n<meta name=\"description\" content=\"Reporting -\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/manpro.id\/product\/reporting\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reporting\" \/>\n<meta property=\"og:description\" content=\"Reporting -\" \/>\n<meta property=\"og:url\" content=\"https:\/\/manpro.id\/product\/reporting\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-21T07:56:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/manpro.id\/product\/wp-content\/uploads\/2023\/02\/Manpro_Logo_mini-e1677825011176.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"381\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/manpro.id\\\/product\\\/reporting\\\/\",\"url\":\"https:\\\/\\\/manpro.id\\\/product\\\/reporting\\\/\",\"name\":\"Reporting -\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/manpro.id\\\/product\\\/#website\"},\"datePublished\":\"2023-03-06T11:28:28+00:00\",\"dateModified\":\"2023-06-21T07:56:25+00:00\",\"description\":\"Reporting -\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/manpro.id\\\/product\\\/reporting\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/manpro.id\\\/product\\\/reporting\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/manpro.id\\\/product\\\/reporting\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/manpro.id\\\/product\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reporting\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/manpro.id\\\/product\\\/#website\",\"url\":\"https:\\\/\\\/manpro.id\\\/product\\\/\",\"name\":\"MANPRO - APLIKASI MANAJEMEN PROYEK\",\"description\":\"Aplikasi Manajemen Proyek\",\"publisher\":{\"@id\":\"https:\\\/\\\/manpro.id\\\/product\\\/#organization\"},\"alternateName\":\"manpro.id\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/manpro.id\\\/product\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/manpro.id\\\/product\\\/#organization\",\"name\":\"MANPRO\",\"url\":\"https:\\\/\\\/manpro.id\\\/product\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/manpro.id\\\/product\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/manpro.id\\\/product\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/manpro-logo-utama.png\",\"contentUrl\":\"https:\\\/\\\/manpro.id\\\/product\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/manpro-logo-utama.png\",\"width\":155,\"height\":47,\"caption\":\"MANPRO\"},\"image\":{\"@id\":\"https:\\\/\\\/manpro.id\\\/product\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/manpro.id\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/pt-manpro-teknologi-indonesia\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@pt.manproteknologiindonesi9678\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Reporting -","description":"Reporting -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/manpro.id\/product\/reporting\/","og_locale":"en_US","og_type":"article","og_title":"Reporting","og_description":"Reporting -","og_url":"https:\/\/manpro.id\/product\/reporting\/","article_modified_time":"2023-06-21T07:56:25+00:00","og_image":[{"width":600,"height":381,"url":"https:\/\/manpro.id\/product\/wp-content\/uploads\/2023\/02\/Manpro_Logo_mini-e1677825011176.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/manpro.id\/product\/reporting\/","url":"https:\/\/manpro.id\/product\/reporting\/","name":"Reporting -","isPartOf":{"@id":"https:\/\/manpro.id\/product\/#website"},"datePublished":"2023-03-06T11:28:28+00:00","dateModified":"2023-06-21T07:56:25+00:00","description":"Reporting -","breadcrumb":{"@id":"https:\/\/manpro.id\/product\/reporting\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/manpro.id\/product\/reporting\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/manpro.id\/product\/reporting\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/manpro.id\/product\/"},{"@type":"ListItem","position":2,"name":"Reporting"}]},{"@type":"WebSite","@id":"https:\/\/manpro.id\/product\/#website","url":"https:\/\/manpro.id\/product\/","name":"MANPRO - APLIKASI MANAJEMEN PROYEK","description":"Aplikasi Manajemen Proyek","publisher":{"@id":"https:\/\/manpro.id\/product\/#organization"},"alternateName":"manpro.id","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/manpro.id\/product\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/manpro.id\/product\/#organization","name":"MANPRO","url":"https:\/\/manpro.id\/product\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/manpro.id\/product\/#\/schema\/logo\/image\/","url":"https:\/\/manpro.id\/product\/wp-content\/uploads\/2023\/08\/manpro-logo-utama.png","contentUrl":"https:\/\/manpro.id\/product\/wp-content\/uploads\/2023\/08\/manpro-logo-utama.png","width":155,"height":47,"caption":"MANPRO"},"image":{"@id":"https:\/\/manpro.id\/product\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/manpro.id\/","https:\/\/www.linkedin.com\/company\/pt-manpro-teknologi-indonesia\/","https:\/\/www.youtube.com\/@pt.manproteknologiindonesi9678"]}]}},"_links":{"self":[{"href":"https:\/\/manpro.id\/product\/wp-json\/wp\/v2\/pages\/3318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manpro.id\/product\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/manpro.id\/product\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/manpro.id\/product\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/manpro.id\/product\/wp-json\/wp\/v2\/comments?post=3318"}],"version-history":[{"count":0,"href":"https:\/\/manpro.id\/product\/wp-json\/wp\/v2\/pages\/3318\/revisions"}],"wp:attachment":[{"href":"https:\/\/manpro.id\/product\/wp-json\/wp\/v2\/media?parent=3318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}